{"id":17647,"date":"2025-03-20T08:28:03","date_gmt":"2025-04-16T22:05:02","guid":{"rendered":"https:\/\/www.ufi.eu\/pcn\/sem categoria\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/"},"modified":"2025-04-16T22:05:02","modified_gmt":"2025-04-16T22:05:02","slug":"pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3","status":"publish","type":"product","link":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/","title":{"rendered":"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas"},"content":{"rendered":"<h2>Como funciona o servi\u00e7o de cria\u00e7\u00e3o de UFI e de notifica\u00e7\u00e3o de PCN?<\/h2>\n<p>Depois de adquirir este servi\u00e7o, receber\u00e1 acesso ao portal seguro. Este portal cont\u00e9m uma vis\u00e3o geral de todas as etapas.  Preencha os dados do seu produto e n\u00f3s come\u00e7amos a trabalhar.<\/p>\n<h3>Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00f5es e UFI<\/h3>\n<p>N\u00f3s forneceremos:<\/p>\n<ul>\n<li>O identificador \u00fanico de f\u00f3rmula (UFI) do seu produto<\/li>\n<li>Um relat\u00f3rio de Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00e3o (PCN)<\/li>\n<li>Registo do seu produto nos Centros Antivenenos nacionais relevantes atrav\u00e9s da ECHA.<\/li>\n<\/ul>\n<h3>Pa\u00edses para registo de NCP<\/h3>\n<p>Pode contar o n\u00famero de pa\u00edses em que pretende registar o seu produto. Este \u00e9 o n\u00famero de pa\u00edses que precisa de comprar.  Poder\u00e1 selecionar os pa\u00edses espec\u00edficos no portal. Se planear expandir as vendas dos seus produtos para novos pa\u00edses numa data posterior, pode sempre encomendar <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/paises\/paises-para-registo-de-ncp\/\" target=\"_blank\" title=\"Registos de pa\u00edses PCN\">registos de pa\u00edses PCN<\/a> adicionais.<br \/>A UE tem 27 pa\u00edses e o EEE tem 30 (UE+Lichtenstein, Noruega e Isl\u00e2ndia) No portal, pode selecionar estes pa\u00edses: <\/p>\n<table cellpadding=\"2\" cellspacing=\"0\" border=\"1\">\n<tbody>\n<tr>\n<td>B\u00e9lgica<\/td>\n<td>(BE)<\/td>\n<td>Espanha<\/td>\n<td>(ES)<\/td>\n<td>Hungria<\/td>\n<td>(HU)<\/td>\n<td>Eslov\u00e1quia<\/td>\n<td>(SK)<\/td>\n<\/tr>\n<tr>\n<td>Bulg\u00e1ria<\/td>\n<td>(BG)<\/td>\n<td>Fran\u00e7a<\/td>\n<td>(FR)<\/td>\n<td>Malta<\/td>\n<td>(MT)<\/td>\n<td>Finl\u00e2ndia<\/td>\n<td>(FI)<\/td>\n<\/tr>\n<tr>\n<td>Rep\u00fablica Checa<\/td>\n<td>(CZ)<\/td>\n<td>Cro\u00e1cia<\/td>\n<td>(HR)<\/td>\n<td>Pa\u00edses Baixos<\/td>\n<td>(NL)<\/td>\n<td>Su\u00e9cia<\/td>\n<td>(SE)<\/td>\n<\/tr>\n<tr>\n<td>Dinamarca<\/td>\n<td>(DK)<\/td>\n<td>It\u00e1lia<\/td>\n<td>(IT)<\/td>\n<td>\u00c1ustria<\/td>\n<td>(AT)<\/td>\n<td>Alemanha<\/td>\n<td>(DE)<\/td>\n<\/tr>\n<tr>\n<td>Chipre<\/td>\n<td>(CY)<\/td>\n<td>Pol\u00f3nia<\/td>\n<td>(PL)<\/td>\n<td>Isl\u00e2ndia<\/td>\n<td>(IS)<\/td>\n<td>Est\u00f3nia<\/td>\n<td>(EE)<\/td>\n<\/tr>\n<tr>\n<td>Let\u00f3nia<\/td>\n<td>(LV)<\/td>\n<td>Portugal<\/td>\n<td>(PT)<\/td>\n<td>Liechtenstein<\/td>\n<td>(LI)<\/td>\n<td>Irlanda<\/td>\n<td>(IE)<\/td>\n<\/tr>\n<tr>\n<td>Litu\u00e2nia<\/td>\n<td>(LT)<\/td>\n<td>Rom\u00e9nia<\/td>\n<td>(RO)<\/td>\n<td>Noruega<\/td>\n<td>(N\u00c3O)<\/td>\n<td>Gr\u00e9cia<\/td>\n<td>(EL)<\/td>\n<\/tr>\n<tr>\n<td>Luxemburgo<\/td>\n<td>(LU)<\/td>\n<td>Eslov\u00e9nia<\/td>\n<td>(SI)<\/td>\n<td>Su\u00ed\u00e7a*<\/td>\n<td>(CH)<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*Para a Su\u00ed\u00e7a, podemos criar o dossier PCN, com todas as informa\u00e7\u00f5es necess\u00e1rias para efetuar uma apresenta\u00e7\u00e3o no portal su\u00ed\u00e7o. Contacte-nos para mais informa\u00e7\u00f5es. <\/p>\n<h3>Informa\u00e7\u00f5es do r\u00f3tulo CLP<\/h3>\n<p>Oferecemos a op\u00e7\u00e3o de adquirir um r\u00f3tulo de produto em conformidade com o CLP, contendo todas as informa\u00e7\u00f5es obrigat\u00f3rias exigidas pelo Regulamento CLP da UE. Este ser\u00e1 fornecido em formato PDF.  N\u00e3o se trata de um desenho, mas de um resumo das informa\u00e7\u00f5es necess\u00e1rias. Isto permitir-lhe-\u00e1 integrar as informa\u00e7\u00f5es necess\u00e1rias na conce\u00e7\u00e3o do r\u00f3tulo do seu produto. Tamb\u00e9m pode encomendar a <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/rotulo-clp\/criacao-de-rotulos-clp-e-verificacao-da-conformidade\/\" target=\"_blank\" title=\"CLP labelcCreation\">cria\u00e7\u00e3o do r\u00f3tulo CLP<\/a> separadamente. J\u00e1 tem um r\u00f3tulo? &#8211; Podemos efetuar uma <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/rotulo-clp\/criacao-de-rotulos-clp-e-verificacao-da-conformidade\/\" target=\"_blank\" title=\"Verifica\u00e7\u00e3o da conformidade do r\u00f3tulo CLP\">verifica\u00e7\u00e3o da conformidade<\/a> do seu r\u00f3tulo com o Regulamento CRE, de acordo com os requisitos actuais do Regulamento CRE. Forneceremos feedback detalhado e correc\u00e7\u00f5es para garantir que o seu r\u00f3tulo cumpre todas as normas regulamentares.     <\/p>\n<h2>Notifica\u00e7\u00e3o do centro antiveneno para produtos de limpeza de cozinha e afins<\/h2>\n<p>Os produtos de limpeza de cozinha e afins, com exce\u00e7\u00e3o dos produtos biocidas, descalcificantes e produtos de limpeza abrasivos, cont\u00eam frequentemente subst\u00e2ncias qu\u00edmicas que podem representar riscos para a sa\u00fade. Estes produtos, que s\u00e3o normalmente utilizados em ambientes de cozinha para a limpeza de superf\u00edcies, utens\u00edlios e aparelhos, devem ser registados no Centro Antivenenos atrav\u00e9s de uma Notifica\u00e7\u00e3o do Centro Antivenenos (PCN). Este registo garante que os dados de seguran\u00e7a, como a composi\u00e7\u00e3o qu\u00edmica, as informa\u00e7\u00f5es sobre os perigos e as instru\u00e7\u00f5es de primeiros socorros, s\u00e3o facilmente acess\u00edveis \u00e0s equipas de emerg\u00eancia em caso de exposi\u00e7\u00e3o acidental ou envenenamento.  <\/p>\n<h3>O que \u00e9 um UFI?<\/h3>\n<p>O Identificador \u00danico de F\u00f3rmula (UFI) \u00e9 um c\u00f3digo \u00fanico atribu\u00eddo a cada f\u00f3rmula de produto. Para produtos de limpeza de cozinha e afins, o UFI permite que as equipas de emerg\u00eancia identifiquem rapidamente a formula\u00e7\u00e3o qu\u00edmica exacta do produto. Isto ajuda a administrar prontamente o tratamento m\u00e9dico correto em caso de exposi\u00e7\u00e3o acidental.  <\/p>\n<h3>O que \u00e9 um PCN?<\/h3>\n<p>Uma Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00f5es (PCN) \u00e9 um requisito para que os fabricantes de produtos perigosos, tais como produtos de limpeza de cozinhas, apresentem os principais dados de seguran\u00e7a ao Centro de Intoxica\u00e7\u00f5es. Estes dados incluem pormenores como a composi\u00e7\u00e3o qu\u00edmica do produto, os perigos para a sa\u00fade associados, medidas de primeiros socorros e informa\u00e7\u00f5es sobre o manuseamento seguro. O PCN assegura que as equipas de emerg\u00eancia est\u00e3o preparadas com a informa\u00e7\u00e3o certa para lidar eficazmente com os incidentes de envenenamento.  <\/p>\n<h3>O que \u00e9 o CLP?<\/h3>\n<p>CLP significa Classifica\u00e7\u00e3o, Rotulagem e Embalagem, que \u00e9 um regulamento da UE que classifica os produtos qu\u00edmicos com base nos seus perigos. No caso dos produtos de limpeza para cozinha e afins, o CRE garante que os produtos s\u00e3o corretamente rotulados com s\u00edmbolos de perigo, recomenda\u00e7\u00f5es de precau\u00e7\u00e3o e instru\u00e7\u00f5es de primeiros socorros. Isto facilita aos consumidores a utiliza\u00e7\u00e3o segura dos produtos e fornece \u00e0s equipas de emerg\u00eancia informa\u00e7\u00f5es essenciais, se necess\u00e1rio.  <\/p>\n<h3>O que \u00e9 o Centro de Intoxica\u00e7\u00f5es?<\/h3>\n<p>O Centro de Intoxica\u00e7\u00f5es \u00e9 uma autoridade centralizada respons\u00e1vel pela manuten\u00e7\u00e3o de uma base de dados de seguran\u00e7a para produtos perigosos. O seu papel \u00e9 garantir que as equipas de emerg\u00eancia tenham acesso imediato a informa\u00e7\u00f5es de seguran\u00e7a precisas em caso de envenenamento ou exposi\u00e7\u00e3o a produtos qu\u00edmicos. Os fabricantes s\u00e3o obrigados a registar os seus produtos no Centro de Intoxica\u00e7\u00f5es para fornecer esta informa\u00e7\u00e3o crucial para fins de sa\u00fade e seguran\u00e7a.  <\/p>\n<h3>Porque \u00e9 que isto \u00e9 necess\u00e1rio?<\/h3>\n<p>Os produtos de limpeza de cozinha e afins, embora eficazes na limpeza, podem conter subst\u00e2ncias qu\u00edmicas nocivas se forem acidentalmente ingeridos, inalados ou entrarem em contacto com a pele. A apresenta\u00e7\u00e3o de uma Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00f5es (PCN) ajuda a garantir que as equipas de emerg\u00eancia disp\u00f5em de todos os dados de seguran\u00e7a necess\u00e1rios, como a composi\u00e7\u00e3o qu\u00edmica e as medidas de primeiros socorros, para tratar os incidentes de exposi\u00e7\u00e3o de forma r\u00e1pida e eficaz. <\/p>\n<h3>Desde quando \u00e9 que isto \u00e9 obrigat\u00f3rio por lei?<\/h3>\n<p>O requisito de apresenta\u00e7\u00e3o de uma Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00f5es (PCN) para produtos perigosos, incluindo produtos de limpeza de cozinha e afins, tornou-se obrigat\u00f3rio em 1 de janeiro de 2021. Esta legisla\u00e7\u00e3o foi introduzida para garantir que todos os produtos qu\u00edmicos perigosos s\u00e3o registados no Centro Antivenenos, permitindo respostas r\u00e1pidas em caso de emerg\u00eancia e uma melhor prote\u00e7\u00e3o da sa\u00fade p\u00fablica. <\/p>\n<h2>FAQ<\/h2>\n<h3>Quest\u00e3o: Os produtos de limpeza de cozinha e afins t\u00eam de ser registados no Centro Antivenenos?<\/h3>\n<p>Resposta: Sim, os produtos de limpeza para cozinha e afins que contenham ingredientes perigosos devem ser registados no Centro Antivenenos. Isto assegura que as equipas de emerg\u00eancia t\u00eam acesso a informa\u00e7\u00f5es de seguran\u00e7a importantes em caso de exposi\u00e7\u00e3o acidental ou envenenamento. <\/p>\n<h3>Quest\u00e3o: Qual \u00e9 o UFI para produtos de limpeza de cozinha e afins?<\/h3>\n<p>Resposta: O UFI (Unique Formula Identifier) \u00e9 um c\u00f3digo \u00fanico que identifica a formula\u00e7\u00e3o espec\u00edfica de um produto. Para produtos de limpeza de cozinha e afins, o UFI ajuda as equipas de emerg\u00eancia a conhecer a composi\u00e7\u00e3o qu\u00edmica exacta do produto, o que \u00e9 crucial para administrar o tratamento m\u00e9dico adequado em caso de exposi\u00e7\u00e3o. <\/p>\n<h3>Quest\u00e3o: Porque \u00e9 que \u00e9 necess\u00e1ria uma Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00e3o (PCN) para produtos de limpeza de cozinha e afins?<\/h3>\n<p>Resposta: \u00c9 necess\u00e1rio um PCN para produtos de limpeza de cozinha e afins para garantir que as equipas de emerg\u00eancia t\u00eam acesso a dados de seguran\u00e7a vitais, incluindo a composi\u00e7\u00e3o qu\u00edmica, os perigos para a sa\u00fade e as instru\u00e7\u00f5es de primeiros socorros. Isto ajuda as equipas de interven\u00e7\u00e3o a agir r\u00e1pida e eficazmente em caso de exposi\u00e7\u00e3o acidental. <\/p>\n<h3>Quest\u00e3o: Como \u00e9 que o Regulamento CRE se aplica aos produtos de limpeza de cozinha e afins?<\/h3>\n<p>Resposta: Os regulamentos CLP (Classifica\u00e7\u00e3o, Rotulagem e Embalagem) exigem que os produtos de limpeza de cozinha e afins sejam rotulados com s\u00edmbolos de perigo, declara\u00e7\u00f5es de precau\u00e7\u00e3o e instru\u00e7\u00f5es de primeiros socorros. Isto garante que os consumidores utilizam os produtos de forma segura e que as equipas de emerg\u00eancia t\u00eam a informa\u00e7\u00e3o necess\u00e1ria em caso de exposi\u00e7\u00e3o. <\/p>\n<h3>Quest\u00e3o: Quando \u00e9 que o requisito PCN para os produtos de limpeza de cozinha perigosos se tornou lei?<\/h3>\n<p>Resposta: O requisito do PCN para produtos perigosos, incluindo produtos de limpeza de cozinha, tornou-se obrigat\u00f3rio a 1 de janeiro de 2021.<\/p>\n<h3>Quest\u00e3o: Quanto tempo \u00e9 necess\u00e1rio para apresentar a notifica\u00e7\u00e3o UFI e PCN?<\/h3>\n<p>S\u00e3o necess\u00e1rios alguns dias de trabalho. Assim que carregar a documenta\u00e7\u00e3o, come\u00e7aremos de imediato. <\/p>\n<h3>Quest\u00e3o: Sou o propriet\u00e1rio da notifica\u00e7\u00e3o PCN?<\/h3>\n<p>Sim, \u00e9 o propriet\u00e1rio da notifica\u00e7\u00e3o PCN. Mant\u00e9m a propriedade total dos dados que forneceu.  A notifica\u00e7\u00e3o PCN estar\u00e1 acess\u00edvel na sua conta ECHA.<\/p>\n<h3>Quest\u00e3o: Este servi\u00e7o \u00e9 para um ou mais produtos?<\/h3>\n<p>O servi\u00e7o \u00e9 para um produto.<\/p>\n<h3>Quest\u00e3o: Porque \u00e9 que tenho de pagar para criar um UFI?<\/h3>\n<p>O servi\u00e7o que oferecemos n\u00e3o se limita a fornecer uma UFI. A UFI \u00e9 uma componente de um processo muito mais alargado.  O principal servi\u00e7o que prestamos \u00e9 a prepara\u00e7\u00e3o e apresenta\u00e7\u00e3o da sua Notifica\u00e7\u00e3o de Centro de Intoxica\u00e7\u00e3o (PCN) aos organismos nacionais designados atrav\u00e9s do portal da ECHA, que \u00e9 um requisito obrigat\u00f3rio ao abrigo do Regulamento CLP da UE para a coloca\u00e7\u00e3o de misturas perigosas no mercado. A cria\u00e7\u00e3o de uma UFI \u00e9 a parte mais simples. O relat\u00f3rio PCN, no entanto, \u00e9 complexo. Exige uma an\u00e1lise pormenorizada dos ingredientes &#8211; classifica\u00e7\u00f5es qu\u00edmicas &#8211; formatadas com precis\u00e3o para apresenta\u00e7\u00e3o ao Centro Antivenenos atrav\u00e9s da ECHA.   <\/p>\n<h3>Quest\u00e3o: A minha empresa n\u00e3o est\u00e1 sediada na UE, como \u00e9 que posso apresentar um PCN?<\/h3>\n<p>Oferecemos uma solu\u00e7\u00e3o para as empresas que n\u00e3o est\u00e3o sediadas na UE. Pode encontrar mais informa\u00e7\u00f5es na p\u00e1gina <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/fora-da-ue\/pcn-e-ufi-para-empresas-nao-comunitarias\/\" target=\"_blank\" rel=\"noopener\">PCN &amp; UFI para empresas n\u00e3o comunit\u00e1rias<\/a>. <\/p>\n<h3>Quest\u00e3o: Podem fornecer fichas de dados de seguran\u00e7a em total conformidade com o Regulamento da UE (REACH e CLP)?<\/h3>\n<p>Sim, podemos <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/ficha-de-dados-de-seguranca\/servico-de-criacao-de-fichas-de-dados-de-seguranca-msds-sds\/\" target=\"_blank\"><strong>criar Fichas de Dados de Seguran\u00e7a (FDS)<\/strong><\/a>&#8211; tamb\u00e9m conhecidas como <strong>Fichas de Dados de Seguran\u00e7a do Material (MSDS<\/strong>) &#8211; adaptadas ao seu produto e em conformidade com os mais recentes regulamentos da UE. Quer esteja a fabricar misturas qu\u00edmicas, a importar produtos para a UE ou a distribuir sob uma marca privada, uma FDS em conformidade \u00e9 legalmente exigida e essencial para uma utiliza\u00e7\u00e3o segura em toda a cadeia de abastecimento. Para mais informa\u00e7\u00f5es, consulte a p\u00e1gina <a href=\"https:\/\/www.ufi.eu\/pt-pt\/pcn\/ficha-de-dados-de-seguranca\/servico-de-criacao-de-fichas-de-dados-de-seguranca-msds-sds\/\" target=\"_blank\">do servi\u00e7o de cria\u00e7\u00e3o de fichas de dados de seguran\u00e7a (MSDS\/SDS)<\/a>.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como funciona o servi\u00e7o de cria\u00e7\u00e3o de UFI e de notifica\u00e7\u00e3o de PCN? Depois de adquirir este servi\u00e7o, receber\u00e1 acesso ao portal seguro. Este portal cont\u00e9m uma vis\u00e3o geral de todas as etapas. Preencha os dados do seu produto e n\u00f3s come\u00e7amos a trabalhar. Notifica\u00e7\u00e3o do Centro de Intoxica\u00e7\u00f5es e UFI N\u00f3s forneceremos: O identificador [&hellip;]<\/p>\n","protected":false},"featured_media":17648,"template":"","meta":[],"product_brand":[],"product_cat":[872],"product_tag":[],"class_list":{"0":"post-17647","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-produtos-de-limpeza-para-cozinha","8":"first","9":"instock","10":"virtual","11":"taxable","12":"purchasable","13":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}},"regular_price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}}},"bundled_items":[{"bundled_item_id":6350,"product_id":12579,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":6351,"product_id":12567,"menu_order":1,"quantity_min":1,"quantity_max":"","quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas - UFI<\/title>\n<meta name=\"description\" content=\"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas\" \/>\n<meta property=\"og:description\" content=\"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"pre\u00e7o\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;0.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilidade\" \/>\n\t<meta name=\"twitter:data2\" content=\"Em stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/\",\"url\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/\",\"name\":\"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas - UFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg\",\"datePublished\":\"2025-04-16T22:05:02+00:00\",\"description\":\"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/pt-pt\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/www.ufi.eu\/pt-pt\/loja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#website\",\"url\":\"https:\/\/www.ufi.eu\/pt-pt\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/pt-pt\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"PC-CLN10\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas - UFI","description":"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/","og_locale":"pt_PT","og_type":"article","og_title":"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas","og_description":"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.","og_url":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/","og_site_name":"UFI","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"pre\u00e7o":"&euro;0.00","Disponibilidade":"Em stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/","url":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/","name":"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas - UFI","isPartOf":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg","datePublished":"2025-04-16T22:05:02+00:00","description":"Assegurar a conformidade PCN e UFI para produtos de limpeza n\u00e3o biocidas. Tratamos das notifica\u00e7\u00f5es do centro de veneno e dos identificadores de f\u00f3rmula \u00fanicos para si.","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CLN10.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/pt-pt\/product\/pcn-ufi-para-produtos-de-limpeza-nao-biocidas-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/pt-pt\/inicio\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/www.ufi.eu\/pt-pt\/loja\/"},{"@type":"ListItem","position":3,"name":"PCN &amp; UFI para produtos de limpeza n\u00e3o biocidas"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/pt-pt\/#website","url":"https:\/\/www.ufi.eu\/pt-pt\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/pt-pt\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.ufi.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/pt-pt\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"PC-CLN10","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/product\/17647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/media\/17648"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=17647"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=17647"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=17647"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=17647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}