{"id":13026,"date":"2025-03-20T08:23:56","date_gmt":"2025-04-15T21:23:28","guid":{"rendered":"https:\/\/www.ufi.eu\/pcn\/non class\u00e9\/pcn-et-ufi-pour-les-produits-de-mortier\/"},"modified":"2025-04-15T21:23:28","modified_gmt":"2025-04-15T21:23:28","slug":"pcn-et-ufi-pour-les-produits-de-mortier","status":"publish","type":"product","link":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/","title":{"rendered":"PCN et UFI pour les produits de mortier"},"content":{"rendered":"<h2>Comment fonctionne le service de cr\u00e9ation d&#8217;UFI et de notification de PCN ?<\/h2>\n<p>Apr\u00e8s avoir achet\u00e9 ce service, vous recevrez un acc\u00e8s au portail s\u00e9curis\u00e9. Ce portail contient une vue d&#8217;ensemble de toutes les \u00e9tapes.  Vous indiquez les d\u00e9tails de votre produit et nous nous mettons au travail.<\/p>\n<h3>Notification au centre antipoison et UFI<\/h3>\n<p>Nous vous fournirons :<\/p>\n<ul>\n<li>L&#8217;identifiant unique de votre produit (UFI)<\/li>\n<li>Un rapport de notification au centre antipoison (PCN)<\/li>\n<li>Enregistrement de votre produit aupr\u00e8s des centres antipoison nationaux comp\u00e9tents via l&#8217;ECHA.<\/li>\n<\/ul>\n<h3>Pays pour l&#8217;enregistrement des NCP<\/h3>\n<p>Vous pouvez compter le nombre de pays dans lesquels vous souhaitez enregistrer votre produit. C&#8217;est le nombre de pays que vous devez acheter.  Vous pourrez s\u00e9lectionner les pays sp\u00e9cifiques dans le portail. Si vous envisagez d&#8217;\u00e9tendre ult\u00e9rieurement la vente de vos produits \u00e0 de nouveaux pays, vous pouvez toujours commander des <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/pays\/pays-pour-lenregistrement-des-ncp\/\" target=\"_blank\" title=\"Enregistrements nationaux du PCN\">enregistrements de pays PCN<\/a> suppl\u00e9mentaires.<br \/>L&#8217;UE compte 27 pays et l&#8217;EEE 30 (UE + Liechtenstein, Norv\u00e8ge et Islande) : <\/p>\n<table cellpadding=\"2\" cellspacing=\"0\" border=\"1\">\n<tbody>\n<tr>\n<td>Belgique<\/td>\n<td>(BE)<\/td>\n<td>Espagne<\/td>\n<td>(ES)<\/td>\n<td>Hongrie<\/td>\n<td>(HU)<\/td>\n<td>Slovaquie<\/td>\n<td>(SK)<\/td>\n<\/tr>\n<tr>\n<td>Bulgarie<\/td>\n<td>(BG)<\/td>\n<td>France<\/td>\n<td>(FR)<\/td>\n<td>Malte<\/td>\n<td>(MT)<\/td>\n<td>Finlande<\/td>\n<td>(FI)<\/td>\n<\/tr>\n<tr>\n<td>Tch\u00e9coslovaquie<\/td>\n<td>(CZ)<\/td>\n<td>Croatie<\/td>\n<td>(HR)<\/td>\n<td>Pays-Bas<\/td>\n<td>(NL)<\/td>\n<td>Su\u00e8de<\/td>\n<td>(SE)<\/td>\n<\/tr>\n<tr>\n<td>Danemark<\/td>\n<td>(DK)<\/td>\n<td>Italie<\/td>\n<td>(IT)<\/td>\n<td>Autriche<\/td>\n<td>(AT)<\/td>\n<td>Allemagne<\/td>\n<td>(DE)<\/td>\n<\/tr>\n<tr>\n<td>Chypre<\/td>\n<td>(CY)<\/td>\n<td>Pologne<\/td>\n<td>(PL)<\/td>\n<td>Islande<\/td>\n<td>(IS)<\/td>\n<td>Estonie<\/td>\n<td>(EE)<\/td>\n<\/tr>\n<tr>\n<td>Lettonie<\/td>\n<td>(LV)<\/td>\n<td>Portugal<\/td>\n<td>(PT)<\/td>\n<td>Liechtenstein<\/td>\n<td>(LI)<\/td>\n<td>Irlande<\/td>\n<td>(IE)<\/td>\n<\/tr>\n<tr>\n<td>Lituanie<\/td>\n<td>(LT)<\/td>\n<td>Roumanie<\/td>\n<td>(RO)<\/td>\n<td>Norv\u00e8ge<\/td>\n<td>(NON)<\/td>\n<td>Gr\u00e8ce<\/td>\n<td>(EL)<\/td>\n<\/tr>\n<tr>\n<td>Luxembourg<\/td>\n<td>(LU)<\/td>\n<td>Slov\u00e9nie<\/td>\n<td>(SI)<\/td>\n<td>Suisse*<\/td>\n<td>(CH)<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*Pour la Suisse, nous pouvons cr\u00e9er le dossier PCN, avec toutes les informations n\u00e9cessaires pour effectuer une soumission dans le portail suisse. Contactez-nous pour plus d&#8217;informations. <\/p>\n<h3>Informations sur l&#8217;\u00e9tiquette CLP<\/h3>\n<p>Nous vous proposons d&#8217;acheter une \u00e9tiquette de produit conforme au r\u00e8glement CLP, contenant toutes les informations obligatoires requises par le r\u00e8glement CLP de l&#8217;UE. Cette \u00e9tiquette vous sera fournie au format PDF.  Il ne s&#8217;agit pas d&#8217;un mod\u00e8le, mais d&#8217;un r\u00e9sum\u00e9 des informations requises. Cela vous permettra d&#8217;int\u00e9grer les informations n\u00e9cessaires dans la conception de l&#8217;\u00e9tiquette de votre produit. Vous pouvez \u00e9galement commander s\u00e9par\u00e9ment la <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/etiquette-clp\/creation-detiquettes-clp-et-controle-de-conformite\/\" target=\"_blank\" title=\"Labellisation CLP\">cr\u00e9ation de l&#8217;\u00e9tiquette CLP<\/a>. Vous avez d\u00e9j\u00e0 une \u00e9tiquette ? &#8211; Nous pouvons <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/etiquette-clp\/creation-detiquettes-clp-et-controle-de-conformite\/\" target=\"_blank\" title=\"V\u00e9rification de la conformit\u00e9 de l'\u00e9tiquette CLP\">v\u00e9rifier la conformit\u00e9 de<\/a> votre \u00e9tiquette aux exigences CLP en vigueur. Nous vous fournirons des commentaires d\u00e9taill\u00e9s et des corrections afin de garantir que votre \u00e9tiquette r\u00e9pond \u00e0 toutes les normes r\u00e9glementaires.     <\/p>\n<h2>Notification au centre antipoison pour les mortiers<\/h2>\n<p>Les mortiers englobent une large gamme de m\u00e9langes \u00e0 base de ciment, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration, les pl\u00e2tres et les enduits, les chapes et les adh\u00e9sifs \u00e0 base de ciment. Ces produits contiennent souvent du ciment, des agr\u00e9gats et divers additifs qui peuvent pr\u00e9senter des risques pour la sant\u00e9 en cas d&#8217;inhalation accidentelle, d&#8217;ingestion ou de contact direct avec la peau ou les yeux \u00e0 l&#8217;\u00e9tat frais (non durci). En vertu de la r\u00e9glementation europ\u00e9enne, si ces mortiers sont class\u00e9s comme dangereux, ils doivent faire l&#8217;objet d&#8217;une notification au centre antipoison (NAP). En soumettant une PCN, les fabricants et les distributeurs permettent aux centres antipoison d&#8217;acc\u00e9der \u00e0 des donn\u00e9es de s\u00e9curit\u00e9 cruciales &#8211; telles que la composition chimique, la classification des dangers et les mesures de premiers secours recommand\u00e9es &#8211; en cas d&#8217;exposition accidentelle.   <\/p>\n<h3>Qu&#8217;est-ce qu&#8217;une UFI ?<\/h3>\n<p>L&#8217;identificateur unique de formule (UFI) est un code alphanum\u00e9rique de 16 caract\u00e8res qui identifie pr\u00e9cis\u00e9ment la formulation chimique d&#8217;un produit dangereux. Pour les mortiers qui r\u00e9pondent aux crit\u00e8res de dangerosit\u00e9, ce code doit figurer sur l&#8217;\u00e9tiquette du produit (souvent \u00e0 c\u00f4t\u00e9 des mentions de s\u00e9curit\u00e9 ou des symboles de danger). En cas d&#8217;urgence, les centres antipoison se r\u00e9f\u00e8rent \u00e0 l&#8217;UFI pour d\u00e9terminer la composition exacte du produit, garantissant ainsi une orientation m\u00e9dicale ou de premiers soins pr\u00e9cise et rapide.  <\/p>\n<h3>Qu&#8217;est-ce qu&#8217;une NCP ?<\/h3>\n<p>La notification au centre antipoison (PCN) est obligatoire en vertu de la l\u00e9gislation de l&#8217;UE pour les m\u00e9langes chimiques dangereux. En soumettant une PCN pour les mortiers, les producteurs et les importateurs fournissent aux centres antipoison des informations d\u00e9taill\u00e9es sur la composition du produit, la classification des dangers, les d\u00e9tails de l&#8217;emballage et les instructions d&#8217;utilisation. Cette base de connaissances permet aux professionnels de la sant\u00e9 et aux intervenants d&#8217;urgence de traiter efficacement les expositions accidentelles, qu&#8217;elles soient dues \u00e0 l&#8217;inhalation ou au contact de la peau ou des yeux avec du mortier frais.  <\/p>\n<h3>Qu&#8217;est-ce que le CLP ?<\/h3>\n<p>Le r\u00e8glement relatif \u00e0 la classification, \u00e0 l&#8217;\u00e9tiquetage et \u00e0 l&#8217;emballage (CLP) normalise la communication des risques chimiques dans les \u00c9tats membres de l&#8217;UE. Les mortiers jug\u00e9s dangereux doivent comporter des symboles de danger appropri\u00e9s, des conseils de prudence et l&#8217;UFI sur leurs \u00e9tiquettes. Cette approche de l&#8217;\u00e9tiquetage aide les utilisateurs \u00e0 comprendre les risques potentiels et \u00e0 mettre en \u0153uvre des pratiques de manipulation s\u00fbres.  <\/p>\n<h3>Qu&#8217;est-ce que le centre antipoison ?<\/h3>\n<p>Le centre antipoison est un r\u00e9seau de centres antipoison nationaux qui offrent des conseils urgents et une orientation m\u00e9dicale en cas d&#8217;exposition \u00e0 des produits chimiques. En enregistrant les produits \u00e0 base de mortier (class\u00e9s comme dangereux) avec un PCN, les entreprises permettent aux centres antipoison de r\u00e9cup\u00e9rer rapidement les donn\u00e9es relatives au danger et \u00e0 la s\u00e9curit\u00e9 du produit, ce qui rationalise la r\u00e9ponse en cas de contact accidentel ou d&#8217;utilisation abusive. <\/p>\n<h3>Pourquoi est-ce n\u00e9cessaire ?<\/h3>\n<p>Les mortiers contiennent g\u00e9n\u00e9ralement du ciment et d&#8217;autres additifs actifs qui, \u00e0 l&#8217;\u00e9tat frais, peuvent provoquer des irritations cutan\u00e9es, des br\u00fblures chimiques ou des probl\u00e8mes respiratoires. Un PCN permet aux centres antipoison d&#8217;acc\u00e9der instantan\u00e9ment \u00e0 des informations vitales sur la s\u00e9curit\u00e9, r\u00e9duisant ainsi les risques pour la sant\u00e9 des travailleurs, des utilisateurs finaux et des autres personnes qui manipulent ces mat\u00e9riaux. Cela permet \u00e9galement de rester en conformit\u00e9 avec les r\u00e9glementations europ\u00e9ennes en mati\u00e8re de s\u00e9curit\u00e9.  <\/p>\n<h3>Depuis quand cette obligation l\u00e9gale existe-t-elle ?<\/h3>\n<p>Depuis le 1er janvier 2021, le r\u00e8glement CLP de l&#8217;UE stipule que tous les m\u00e9langes chimiques dangereux, y compris certains mortiers, doivent \u00eatre enregistr\u00e9s au moyen d&#8217;un NCP. Cette exigence harmonis\u00e9e permet de maintenir des protocoles d&#8217;intervention d&#8217;urgence et de s\u00e9curit\u00e9 coh\u00e9rents dans tous les \u00c9tats membres de l&#8217;UE. <\/p>\n<h2>FAQ<\/h2>\n<h3>Question : Tous les produits \u00e0 base de mortier doivent-ils faire l&#8217;objet d&#8217;une NCP ?<\/h3>\n<p>R\u00e9ponse : Seuls les mortiers class\u00e9s comme dangereux en vertu des r\u00e8glements CLP doivent faire l&#8217;objet d&#8217;une NCP. Les m\u00e9langes non dangereux ne n\u00e9cessitent pas cette notification. <\/p>\n<h3>Question : O\u00f9 doit se trouver l&#8217;UFI sur l&#8217;emballage du mortier ?<\/h3>\n<p>R\u00e9ponse : L&#8217;UFI est g\u00e9n\u00e9ralement plac\u00e9 \u00e0 proximit\u00e9 des symboles de danger ou des consignes de s\u00e9curit\u00e9 figurant sur l&#8217;\u00e9tiquette du produit, ce qui le rend facilement accessible en cas d&#8217;urgence.<\/p>\n<h3>Question : Quels d\u00e9tails doivent figurer dans la soumission d&#8217;une NCP pour les mortiers ?<\/h3>\n<p>R\u00e9ponse : Un NCP contient des donn\u00e9es sur la composition chimique du produit, la classification des dangers, le mode d&#8217;emploi, les premiers soins recommand\u00e9s et le format de l&#8217;emballage, que les centres antipoison utilisent pour donner des conseils pr\u00e9cis en cas d&#8217;urgence.<\/p>\n<h3>Question : Les colles non cimentaires sont-elles incluses dans les mortiers ?<\/h3>\n<p>R\u00e9ponse : Non, les colles sans ciment rel\u00e8vent de la cat\u00e9gorie &#8220;Colles et mastics d&#8217;\u00e9tanch\u00e9it\u00e9 &#8211; b\u00e2timents et travaux de construction&#8221;. Les mortiers se r\u00e9f\u00e8rent sp\u00e9cifiquement aux m\u00e9langes \u00e0 base de ciment. <\/p>\n<h3>Question : Qui est responsable de la soumission de la NCP ?<\/h3>\n<p>R\u00e9ponse : Le fabricant, l&#8217;importateur ou le distributeur qui met le mortier dangereux sur le march\u00e9 de l&#8217;UE doit g\u00e9n\u00e9ralement d\u00e9poser une PCN si le m\u00e9lange r\u00e9pond aux crit\u00e8res de danger du CLP.<\/p>\n<h3>Question : Que se passe-t-il si je ne soumets pas de NCP pour un mortier dangereux ?<\/h3>\n<p>R\u00e9ponse : La non-conformit\u00e9 peut entra\u00eener des sanctions juridiques, des amendes ou l&#8217;impossibilit\u00e9 de commercialiser le produit jusqu&#8217;\u00e0 ce que les exigences du PCN soient respect\u00e9es.<\/p>\n<h3>Question : Depuis quand l&#8217;obligation d&#8217;\u00e9tablir un NCP pour les produits dangereux existe-t-elle ?<\/h3>\n<p>R\u00e9ponse : L&#8217;obligation est entr\u00e9e en vigueur le 1er janvier 2021, en vertu du r\u00e8glement CLP de l&#8217;UE, afin de garantir la coh\u00e9rence des mesures de s\u00e9curit\u00e9 et des interventions en cas d&#8217;urgence dans l&#8217;ensemble de l&#8217;UE.<\/p>\n<h3>Question : Combien de temps faut-il pour soumettre la notification UFI et PCN ?<\/h3>\n<p>Il nous faut quelques jours de travail. D\u00e8s que vous aurez t\u00e9l\u00e9charg\u00e9 la documentation, nous commencerons \u00e0 travailler. <\/p>\n<h3>Question : Suis-je le propri\u00e9taire de la notification PCN ?<\/h3>\n<p>Oui, vous \u00eates le propri\u00e9taire de la notification PCN. Vous restez propri\u00e9taire des donn\u00e9es que vous avez fournies.  La notification PCN sera accessible sur votre compte ECHA.<\/p>\n<h3>Question : Ce service concerne-t-il un seul produit ou plusieurs ?<\/h3>\n<p>Le service concerne un seul produit.<\/p>\n<h3>Question : Pourquoi dois-je payer pour cr\u00e9er une UFI ?<\/h3>\n<p>Le service que nous proposons ne se limite pas \u00e0 la fourniture d&#8217;un UFI. L&#8217;UFI est un \u00e9l\u00e9ment d&#8217;un processus beaucoup plus vaste.  Le service principal que nous fournissons est la pr\u00e9paration et la soumission de votre notification au centre antipoison (PCN) aux organismes nationaux d\u00e9sign\u00e9s via le portail de l&#8217;ECHA, ce qui est une exigence obligatoire en vertu du r\u00e8glement CLP de l&#8217;UE pour la mise sur le march\u00e9 de m\u00e9langes dangereux. La production d&#8217;un UFI est la partie la plus simple. Le rapport PCN, en revanche, est complexe. Il exige un examen d\u00e9taill\u00e9 des ingr\u00e9dients, des classifications chimiques et un formatage pr\u00e9cis pour la soumission au centre antipoison par l&#8217;interm\u00e9diaire de l&#8217;ECHA.   <\/p>\n<h3>Question : Mon entreprise n&#8217;est pas bas\u00e9e dans l&#8217;UE, comment puis-je soumettre une NCP ?<\/h3>\n<p>Nous proposons une solution aux entreprises qui ne sont pas bas\u00e9es dans l&#8217;UE. Vous trouverez plus d&#8217;informations sur la page <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/hors-ue\/pcn-et-ufi-pour-les-entreprises-non-europeennes\/\" target=\"_blank\" rel=\"noopener\">PCN &amp; UFI pour les entreprises non europ\u00e9ennes.<\/a>  <\/p>\n<h3>Question : Pouvez-vous fournir des fiches de donn\u00e9es de s\u00e9curit\u00e9 conformes \u00e0 la r\u00e9glementation europ\u00e9enne (REACH et CLP) ?<\/h3>\n<p>Oui, nous pouvons <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/fiche-de-donnees-de-securite\/service-de-creation-de-fiches-de-donnees-de-securite-fds-fds\/\" target=\"_blank\"><strong>cr\u00e9er des fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS)<\/strong><\/a>&#8211; \u00e9galement connues sous le nom de <strong>fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS<\/strong>) &#8211; adapt\u00e9es \u00e0 votre produit et conformes aux derni\u00e8res r\u00e9glementations europ\u00e9ennes. Que vous fabriquiez des m\u00e9langes chimiques, que vous importiez des produits dans l&#8217;UE ou que vous les distribuiez sous une marque priv\u00e9e, une FDS conforme est l\u00e9galement requise et essentielle pour une utilisation s\u00fbre tout au long de la cha\u00eene d&#8217;approvisionnement. Vous trouverez plus d&#8217;informations sur la page du <a href=\"https:\/\/www.ufi.eu\/fr\/pcn\/fiche-de-donnees-de-securite\/service-de-creation-de-fiches-de-donnees-de-securite-fds-fds\/\" target=\"_blank\">service de cr\u00e9ation de fiches de donn\u00e9es de s\u00e9curit\u00e9 (FDS\/SDS)<\/a>.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment fonctionne le service de cr\u00e9ation d&#8217;UFI et de notification de PCN ? Apr\u00e8s avoir achet\u00e9 ce service, vous recevrez un acc\u00e8s au portail s\u00e9curis\u00e9. Ce portail contient une vue d&#8217;ensemble de toutes les \u00e9tapes. Vous indiquez les d\u00e9tails de votre produit et nous nous mettons au travail. Notification au centre antipoison et UFI Nous [&hellip;]<\/p>\n","protected":false},"featured_media":13027,"template":"","meta":[],"product_brand":[],"product_cat":[465],"product_tag":[],"class_list":{"0":"post-13026","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-produits-de-construction","8":"first","9":"instock","10":"virtual","11":"taxable","12":"purchasable","13":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}},"regular_price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}}},"bundled_items":[{"bundled_item_id":1644,"product_id":12547,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":1645,"product_id":12550,"menu_order":1,"quantity_min":1,"quantity_max":"","quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PCN et UFI pour les produits de mortier - UFI<\/title>\n<meta name=\"description\" content=\"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l&#039;UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCN et UFI pour les produits de mortier\" \/>\n<meta property=\"og:description\" content=\"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l&#039;UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;0.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/\",\"url\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/\",\"name\":\"PCN et UFI pour les produits de mortier - UFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg\",\"datePublished\":\"2025-04-15T21:23:28+00:00\",\"description\":\"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l'UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.ufi.eu\/fr\/boutique\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCN et UFI pour les produits de mortier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/#website\",\"url\":\"https:\/\/www.ufi.eu\/fr\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ufi.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/fr\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"PC-CON-4\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PCN et UFI pour les produits de mortier - UFI","description":"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l'UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/","og_locale":"fr_FR","og_type":"article","og_title":"PCN et UFI pour les produits de mortier","og_description":"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l'UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !","og_url":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/","og_site_name":"UFI","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"&euro;0.00","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/","url":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/","name":"PCN et UFI pour les produits de mortier - UFI","isPartOf":{"@id":"https:\/\/www.ufi.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg","datePublished":"2025-04-15T21:23:28+00:00","description":"Obtenez une NCP et une UFI pour les produits \u00e0 base de mortier, y compris les mortiers de ma\u00e7onnerie et de r\u00e9paration. Assurez-vous de la conformit\u00e9 du centre antipoison de l'UE gr\u00e2ce \u00e0 notre service de notification rapide et fiable !","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-CON-4.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/fr\/product\/pcn-et-ufi-pour-les-produits-de-mortier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.ufi.eu\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"PCN et UFI pour les produits de mortier"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/fr\/#website","url":"https:\/\/www.ufi.eu\/fr\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/fr\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ufi.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/fr\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"PC-CON-4","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/product\/13026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/media\/13027"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/media?parent=13026"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=13026"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=13026"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=13026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}