{"id":21301,"date":"2025-03-20T08:25:24","date_gmt":"2025-04-17T09:42:19","guid":{"rendered":"https:\/\/www.ufi.eu\/pcn\/sin categor\u00eda\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/"},"modified":"2025-04-17T09:42:19","modified_gmt":"2025-04-17T09:42:19","slug":"pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos","status":"publish","type":"product","link":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/","title":{"rendered":"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos"},"content":{"rendered":"<h2>\u00bfC\u00f3mo funciona el servicio de creaci\u00f3n de UFI y notificaci\u00f3n de PCN?<\/h2>\n<p>Tras adquirir este servicio, recibir\u00e1 acceso al portal seguro. Este portal contiene un resumen de todos los pasos.  Rellene los datos de su producto y nos pondremos manos a la obra.<\/p>\n<h3>Notificaci\u00f3n al Centro de Intoxicaciones y UFI<\/h3>\n<p>Le proporcionaremos:<\/p>\n<ul>\n<li>El identificador \u00fanico de f\u00f3rmula (UFI) de su producto<\/li>\n<li>Un informe de Notificaci\u00f3n al Centro de Toxicolog\u00eda (PCN)<\/li>\n<li>Registro de su producto en los Centros Nacionales de Toxicolog\u00eda pertinentes a trav\u00e9s de la ECHA.<\/li>\n<\/ul>\n<h3>Pa\u00edses para el registro de NCP<\/h3>\n<p>Puede contar el n\u00famero de pa\u00edses en los que desea registrar su producto. Este es el n\u00famero de pa\u00edses que necesita comprar.  Podr\u00e1 seleccionar los pa\u00edses espec\u00edficos dentro del portal. Si m\u00e1s adelante tiene previsto ampliar las ventas de sus productos a nuevos pa\u00edses, siempre podr\u00e1 solicitar <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/paises-es\/paises-para-el-registro-de-ncp\/\" target=\"_blank\" title=\"Registros de pa\u00edses NCP\">registros de pa\u00edses NCP<\/a> adicionales.<br \/>La UE cuenta con 27 pa\u00edses y el EEE con 30 (UE+Lichtenstein, Noruega e Islandia) En el portal podr\u00e1 seleccionar estos pa\u00edses: <\/p>\n<table cellpadding=\"2\" cellspacing=\"0\" border=\"1\">\n<tbody>\n<tr>\n<td>B\u00e9lgica<\/td>\n<td>(BE)<\/td>\n<td>Espa\u00f1a<\/td>\n<td>(ES)<\/td>\n<td>Hungr\u00eda<\/td>\n<td>(HU)<\/td>\n<td>Eslovaquia<\/td>\n<td>(SK)<\/td>\n<\/tr>\n<tr>\n<td>Bulgaria<\/td>\n<td>(BG)<\/td>\n<td>Francia<\/td>\n<td>(FR)<\/td>\n<td>Malta<\/td>\n<td>(MT)<\/td>\n<td>Finlandia<\/td>\n<td>(FI)<\/td>\n<\/tr>\n<tr>\n<td>Chequia<\/td>\n<td>(CZ)<\/td>\n<td>Croacia<\/td>\n<td>(HR)<\/td>\n<td>Pa\u00edses Bajos<\/td>\n<td>(NL)<\/td>\n<td>Suecia<\/td>\n<td>(SE)<\/td>\n<\/tr>\n<tr>\n<td>Dinamarca<\/td>\n<td>(DK)<\/td>\n<td>Italia<\/td>\n<td>(IT)<\/td>\n<td>Austria<\/td>\n<td>(AT)<\/td>\n<td>Alemania<\/td>\n<td>(DE)<\/td>\n<\/tr>\n<tr>\n<td>Chipre<\/td>\n<td>(CY)<\/td>\n<td>Polonia<\/td>\n<td>(PL)<\/td>\n<td>Islandia<\/td>\n<td>(IS)<\/td>\n<td>Estonia<\/td>\n<td>(EE)<\/td>\n<\/tr>\n<tr>\n<td>Letonia<\/td>\n<td>(LV)<\/td>\n<td>Portugal<\/td>\n<td>(PT)<\/td>\n<td>Liechtenstein<\/td>\n<td>(LI)<\/td>\n<td>Irlanda<\/td>\n<td>(IE)<\/td>\n<\/tr>\n<tr>\n<td>Lituania<\/td>\n<td>(LT)<\/td>\n<td>Ruman\u00eda<\/td>\n<td>(RO)<\/td>\n<td>Noruega<\/td>\n<td>(NO)<\/td>\n<td>Grecia<\/td>\n<td>(EL)<\/td>\n<\/tr>\n<tr>\n<td>Luxemburgo<\/td>\n<td>(LU)<\/td>\n<td>Eslovenia<\/td>\n<td>(SI)<\/td>\n<td>Suiza<\/td>\n<td>(CH)<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*Para Suiza podemos crear el expediente PCN, con toda la informaci\u00f3n necesaria para hacer una presentaci\u00f3n en el portal suizo. P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n. <\/p>\n<h3>Informaci\u00f3n de la etiqueta CLP<\/h3>\n<p>Le ofrecemos la opci\u00f3n de adquirir una etiqueta de producto conforme a CLP, que contiene toda la informaci\u00f3n obligatoria que exige el Reglamento CLP de la UE. Se le proporcionar\u00e1 en formato PDF.  No se trata de un dise\u00f1o, sino de un resumen de la informaci\u00f3n necesaria. Esto le permitir\u00e1 integrar la informaci\u00f3n necesaria en el dise\u00f1o de la etiqueta de su producto.  Tambi\u00e9n puede encargar por separado la <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/etiqueta-clp\/creacion-de-etiquetas-clp-y-comprobacion-del-cumplimiento\/\" target=\"_blank\" title=\"Etiquetado CLPCreaci\u00f3n\">creaci\u00f3n de etiquetas CLP<\/a>. \u00bfYa tiene una etiqueta? &#8211; Podemos realizar una <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/etiqueta-clp\/creacion-de-etiquetas-clp-y-comprobacion-del-cumplimiento\/\" target=\"_blank\" title=\"Comprobaci\u00f3n del cumplimiento de la etiqueta CLP\">comprobaci\u00f3n de conformidad<\/a> de su etiqueta CLP de acuerdo con los requisitos CLP actuales. Le proporcionaremos informaci\u00f3n detallada y correcciones para garantizar que su etiqueta cumple todas las normas reglamentarias.   <\/p>\n<h2>Notificaci\u00f3n al Centro de Toxicolog\u00eda de productos sanitarios para su limpieza o desinfecci\u00f3n<\/h2>\n<p>Los productos utilizados para la limpieza, desinfecci\u00f3n o esterilizaci\u00f3n de productos sanitarios (excluidos los biocidas o productos de limpieza) deben cumplir la normativa de la UE para garantizar la seguridad y la correcta manipulaci\u00f3n en caso de emergencia. Se requiere una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP) para estos productos con el fin de proporcionar al personal de emergencias informaci\u00f3n crucial sobre su composici\u00f3n qu\u00edmica y riesgos potenciales. Al presentar una NCP, los fabricantes garantizan que los profesionales sanitarios y los equipos de emergencia est\u00e9n preparados para responder eficazmente en caso de exposici\u00f3n accidental a los productos qu\u00edmicos peligrosos utilizados en el proceso de desinfecci\u00f3n o esterilizaci\u00f3n.  <\/p>\n<h3>\u00bfQu\u00e9 es un UFI?<\/h3>\n<p>El Identificador de F\u00f3rmula \u00danica (UFI) es un c\u00f3digo \u00fanico asignado a una mezcla qu\u00edmica, como las utilizadas en los productos de limpieza o desinfecci\u00f3n de dispositivos m\u00e9dicos. Este c\u00f3digo forma parte de la etiqueta del producto y ayuda al personal de emergencias a identificar r\u00e1pidamente los componentes qu\u00edmicos de la mezcla. El UFI desempe\u00f1a un papel fundamental para garantizar que se toman las medidas de seguridad adecuadas en situaciones de emergencia.  <\/p>\n<h3>\u00bfQu\u00e9 es un NCP?<\/h3>\n<p>Una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP) es una presentaci\u00f3n que contiene informaci\u00f3n detallada sobre la composici\u00f3n qu\u00edmica de un producto, sus peligros y los procedimientos de respuesta a emergencias. Para los productos utilizados en la limpieza o desinfecci\u00f3n de productos sanitarios, la NCP incluye informaci\u00f3n sobre los ingredientes qu\u00edmicos y su clasificaci\u00f3n seg\u00fan el Reglamento CLP. Esto permite al personal de respuesta a emergencias acceder a datos importantes para gestionar los riesgos de exposici\u00f3n de forma r\u00e1pida y eficaz.  <\/p>\n<h3>\u00bfQu\u00e9 es el CLP?<\/h3>\n<p>El Reglamento sobre clasificaci\u00f3n, etiquetado y envasado (CLP) regula la clasificaci\u00f3n y el etiquetado de los productos qu\u00edmicos peligrosos. Garantiza que los productos, incluidas las soluciones de limpieza y desinfecci\u00f3n para productos sanitarios, est\u00e9n debidamente etiquetados con s\u00edmbolos de peligro, palabras de advertencia e indicaciones de precauci\u00f3n. El CLP es vital para informar a los usuarios de los riesgos asociados a estos productos y garantizar una manipulaci\u00f3n adecuada para evitar accidentes y lesiones.  <\/p>\n<h3>\u00bfQu\u00e9 es el Centro de Toxicolog\u00eda?<\/h3>\n<p>El Centro de Toxicolog\u00eda es una red encargada de recopilar y distribuir informaci\u00f3n sobre sustancias peligrosas utilizadas en productos en toda Europa. Al registrar los productos en el Centro de Toxicolog\u00eda, los fabricantes garantizan que los profesionales sanitarios y el personal de emergencias dispongan de informaci\u00f3n precisa sobre seguridad en caso de exposici\u00f3n accidental o incidente sanitario relacionado con productos de limpieza o desinfecci\u00f3n de productos sanitarios. <\/p>\n<h3>\u00bfPor qu\u00e9 es necesario?<\/h3>\n<p>El NCP para los productos de limpieza o desinfecci\u00f3n de dispositivos m\u00e9dicos es esencial para garantizar que el personal de emergencias disponga de toda la informaci\u00f3n necesaria en caso de exposici\u00f3n a sustancias qu\u00edmicas peligrosas. Estos productos pueden contener ingredientes potencialmente nocivos que requieren una identificaci\u00f3n adecuada y procedimientos de manipulaci\u00f3n de emergencia. Al presentar un NCP, los fabricantes contribuyen a crear un entorno m\u00e1s seguro para los profesionales sanitarios y los pacientes, garantizando respuestas r\u00e1pidas y precisas en caso de accidente.  <\/p>\n<h3>\u00bfDesde cu\u00e1ndo es obligatorio por ley?<\/h3>\n<p>A partir del 1 de enero de 2021, el Anexo VIII del Reglamento CLP de la UE exige que todas las mezclas peligrosas, incluidos los productos para la limpieza, desinfecci\u00f3n o esterilizaci\u00f3n de productos sanitarios (excluidos los biocidas), presenten una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP). Este reglamento ayuda a garantizar que la informaci\u00f3n de seguridad sobre estas sustancias qu\u00edmicas est\u00e9 disponible para los equipos de respuesta a emergencias, mejorando la seguridad y los tiempos de respuesta en toda la UE. <\/p>\n<h2>PREGUNTAS FRECUENTES<\/h2>\n<h3>Pregunta: \u00bfNecesito presentar una NCP para mi producto de limpieza o desinfecci\u00f3n de productos sanitarios?<\/h3>\n<p>Respuesta: S\u00ed, si su producto contiene sustancias peligrosas y se utiliza para la limpieza, desinfecci\u00f3n o esterilizaci\u00f3n de productos sanitarios, est\u00e1 obligado a presentar un NCP. Esto garantiza que los equipos de respuesta a emergencias dispongan de la informaci\u00f3n de seguridad necesaria en caso de que se produzca un incidente de exposici\u00f3n. <\/p>\n<h3>Pregunta: \u00bfQu\u00e9 ocurre si no presento un NCP para mi producto?<\/h3>\n<p>Respuesta: No presentar una NCP puede acarrear sanciones legales, incluidas multas o la retirada de su producto del mercado. Adem\u00e1s, es posible que los equipos de respuesta a emergencias no dispongan de la informaci\u00f3n necesaria para responder adecuadamente en caso de exposici\u00f3n, lo que podr\u00eda provocar riesgos m\u00e1s graves para la salud. <\/p>\n<h3>Pregunta: \u00bfC\u00f3mo presento una NCP para mi producto de limpieza de dispositivos m\u00e9dicos?<\/h3>\n<p>Respuesta: Para presentar una NCP, debe proporcionar informaci\u00f3n detallada sobre la composici\u00f3n qu\u00edmica del producto, su clasificaci\u00f3n seg\u00fan el Reglamento CLP y las medidas de respuesta en caso de emergencia. Ofrecemos servicios para ayudarle a preparar el UFI, la etiqueta del producto y la presentaci\u00f3n del NCP para garantizar el pleno cumplimiento de la normativa de la UE. <\/p>\n<h3>Pregunta: \u00bfCu\u00e1nto tiempo se tarda en presentar la notificaci\u00f3n de UFI y PCN?<\/h3>\n<p>Nos lleva unos d\u00edas de trabajo. En cuanto cargue la documentaci\u00f3n, nos pondremos manos a la obra de inmediato. <\/p>\n<h3>Pregunta: \u00bfSoy el propietario de la notificaci\u00f3n de NCP?<\/h3>\n<p>S\u00ed, usted es el propietario de la notificaci\u00f3n de NCP. Usted conserva la plena propiedad de los datos que ha facilitado.  Podr\u00e1 acceder a la notificaci\u00f3n de la NCP en su cuenta de la ECHA.<\/p>\n<h3>Pregunta: \u00bfEste servicio es para un producto o para varios?<\/h3>\n<p>El servicio es para un solo producto.<\/p>\n<h3>Pregunta: \u00bfPor qu\u00e9 tengo que pagar para crear un UFI?<\/h3>\n<p>El servicio que ofrecemos no consiste \u00fanicamente en proporcionar un IUF. El IUF es un componente dentro de un proceso mucho m\u00e1s amplio.  El principal servicio que ofrecemos es la preparaci\u00f3n y presentaci\u00f3n de su Notificaci\u00f3n del Centro de Intoxicaciones (NIP) a los organismos nacionales designados a trav\u00e9s del portal de la ECHA, que es un requisito obligatorio seg\u00fan el Reglamento CLP de la UE para comercializar mezclas peligrosas. Generar un UFI es la parte m\u00e1s sencilla. El informe NCP, sin embargo, es complejo. Exige una revisi\u00f3n detallada de los ingredientes -clasificaciones qu\u00edmicas- formateada con precisi\u00f3n para su presentaci\u00f3n al Centro de Toxicolog\u00eda a trav\u00e9s de la ECHA.   <\/p>\n<h3>Pregunta: Mi empresa no tiene sede en la UE, \u00bfc\u00f3mo puedo presentar un NCP?<\/h3>\n<p>Ofrecemos una soluci\u00f3n para las empresas que no tienen su sede en la UE. Encontrar\u00e1 m\u00e1s informaci\u00f3n en la p\u00e1gina <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/fuera-de-la-ue\/ncp-y-ufi-para-empresas-de-fuera-de-la-ue\/\" target=\"_blank\" rel=\"noopener\">NCP y UFI para empresas no pertenecientes a la UE<\/a>. <\/p>\n<h3>Pregunta: \u00bfPueden proporcionar fichas de datos de seguridad que cumplan plenamente la normativa de la UE (REACH y CLP)?<\/h3>\n<p>S\u00ed, podemos <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/ficha-de-datos-de-seguridad\/servicio-de-creacion-de-fichas-de-datos-de-seguridad-fds-sds\/\" target=\"_blank\"><strong>crear fichas de datos de seguridad (FDS)<\/strong><\/a>&#8211; tambi\u00e9n conocidas como <strong>Fichas de datos de seguridad de materiales (FDS)<\/strong>&#8211; adaptadas a su producto y conformes con las \u00faltimas normativas de la UE. Tanto si fabrica mezclas qu\u00edmicas, como si importa productos a la UE o los distribuye con una etiqueta privada, una FDS que cumpla la normativa es legalmente obligatoria y esencial para un uso seguro en toda la cadena de suministro. Encontrar\u00e1 m\u00e1s informaci\u00f3n en la p\u00e1gina del <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/ficha-de-datos-de-seguridad\/servicio-de-creacion-de-fichas-de-datos-de-seguridad-fds-sds\/\" target=\"_blank\">Servicio de creaci\u00f3n de fichas de datos de seguridad (FDS\/SDS<\/a> ).  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo funciona el servicio de creaci\u00f3n de UFI y notificaci\u00f3n de PCN? Tras adquirir este servicio, recibir\u00e1 acceso al portal seguro. Este portal contiene un resumen de todos los pasos. Rellene los datos de su producto y nos pondremos manos a la obra. Notificaci\u00f3n al Centro de Intoxicaciones y UFI Le proporcionaremos: El identificador \u00fanico [&hellip;]<\/p>\n","protected":false},"featured_media":21302,"template":"","meta":[],"product_brand":[],"product_cat":[1018],"product_tag":[],"class_list":{"0":"post-21301","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dispositivos-medicos-es","8":"first","9":"instock","10":"virtual","11":"taxable","12":"purchasable","13":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}},"regular_price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}}},"bundled_items":[{"bundled_item_id":10032,"product_id":12583,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":10033,"product_id":12572,"menu_order":1,"quantity_min":1,"quantity_max":"","quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos - UFI<\/title>\n<meta name=\"description\" content=\"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos\" \/>\n<meta property=\"og:description\" content=\"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Precio\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;0.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilidad\" \/>\n\t<meta name=\"twitter:data2\" content=\"Disponible\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/\",\"url\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/\",\"name\":\"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos - UFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg\",\"datePublished\":\"2025-04-17T09:42:19+00:00\",\"description\":\"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.ufi.eu\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"PC-MED-1\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos - UFI","description":"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/","og_locale":"es_ES","og_type":"article","og_title":"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos","og_description":"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.","og_url":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/","og_site_name":"UFI","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Precio":"&euro;0.00","Disponibilidad":"Disponible"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/","url":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/","name":"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos - UFI","isPartOf":{"@id":"https:\/\/www.ufi.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg","datePublished":"2025-04-17T09:42:19+00:00","description":"Obtenga un NCP y un UFI para productos de limpieza y esterilizaci\u00f3n de productos sanitarios. Garantice el cumplimiento del Centro de Toxicolog\u00eda de la UE con nuestro servicio r\u00e1pido y fiable.","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-MED-1.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-productos-de-limpieza-de-dispositivos-medicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.ufi.eu\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"PCN y UFI para productos de limpieza de dispositivos m\u00e9dicos"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/es\/#website","url":"https:\/\/www.ufi.eu\/es\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/es\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"PC-MED-1","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product\/21301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media\/21302"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media?parent=21301"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_brand?post=21301"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_cat?post=21301"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_tag?post=21301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}