{"id":13986,"date":"2025-03-20T08:30:02","date_gmt":"2025-04-16T08:16:58","guid":{"rendered":"https:\/\/www.ufi.eu\/pcn\/sin categor\u00eda\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/"},"modified":"2025-04-16T08:16:58","modified_gmt":"2025-04-16T08:16:58","slug":"pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas","status":"publish","type":"product","link":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/","title":{"rendered":"PCN y UFI para velas perfumadas y no perfumadas"},"content":{"rendered":"<h2>\u00bfC\u00f3mo funciona el servicio de creaci\u00f3n de UFI y notificaci\u00f3n de PCN?<\/h2>\n<p>Tras adquirir este servicio, recibir\u00e1 acceso al portal seguro. Este portal contiene un resumen de todos los pasos.  Rellene los datos de su producto y nos pondremos manos a la obra.<\/p>\n<h3>Notificaci\u00f3n al Centro de Intoxicaciones y UFI<\/h3>\n<p>Le proporcionaremos:<\/p>\n<ul>\n<li>El identificador \u00fanico de f\u00f3rmula (UFI) de su producto<\/li>\n<li>Un informe de Notificaci\u00f3n al Centro de Toxicolog\u00eda (PCN)<\/li>\n<li>Registro de su producto en los Centros Nacionales de Toxicolog\u00eda pertinentes a trav\u00e9s de la ECHA.<\/li>\n<\/ul>\n<h3>Pa\u00edses para el registro de NCP<\/h3>\n<p>Puede contar el n\u00famero de pa\u00edses en los que desea registrar su producto. Este es el n\u00famero de pa\u00edses que necesita comprar.  Podr\u00e1 seleccionar los pa\u00edses espec\u00edficos dentro del portal. Si m\u00e1s adelante tiene previsto ampliar las ventas de sus productos a nuevos pa\u00edses, siempre podr\u00e1 solicitar <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/paises-es\/paises-para-el-registro-de-ncp\/\" target=\"_blank\" title=\"Registros de pa\u00edses NCP\">registros de pa\u00edses NCP<\/a> adicionales.<br \/>La UE cuenta con 27 pa\u00edses y el EEE con 30 (UE+Lichtenstein, Noruega e Islandia) En el portal podr\u00e1 seleccionar estos pa\u00edses: <\/p>\n<table cellpadding=\"2\" cellspacing=\"0\" border=\"1\">\n<tbody>\n<tr>\n<td>B\u00e9lgica<\/td>\n<td>(BE)<\/td>\n<td>Espa\u00f1a<\/td>\n<td>(ES)<\/td>\n<td>Hungr\u00eda<\/td>\n<td>(HU)<\/td>\n<td>Eslovaquia<\/td>\n<td>(SK)<\/td>\n<\/tr>\n<tr>\n<td>Bulgaria<\/td>\n<td>(BG)<\/td>\n<td>Francia<\/td>\n<td>(FR)<\/td>\n<td>Malta<\/td>\n<td>(MT)<\/td>\n<td>Finlandia<\/td>\n<td>(FI)<\/td>\n<\/tr>\n<tr>\n<td>Chequia<\/td>\n<td>(CZ)<\/td>\n<td>Croacia<\/td>\n<td>(HR)<\/td>\n<td>Pa\u00edses Bajos<\/td>\n<td>(NL)<\/td>\n<td>Suecia<\/td>\n<td>(SE)<\/td>\n<\/tr>\n<tr>\n<td>Dinamarca<\/td>\n<td>(DK)<\/td>\n<td>Italia<\/td>\n<td>(IT)<\/td>\n<td>Austria<\/td>\n<td>(AT)<\/td>\n<td>Alemania<\/td>\n<td>(DE)<\/td>\n<\/tr>\n<tr>\n<td>Chipre<\/td>\n<td>(CY)<\/td>\n<td>Polonia<\/td>\n<td>(PL)<\/td>\n<td>Islandia<\/td>\n<td>(IS)<\/td>\n<td>Estonia<\/td>\n<td>(EE)<\/td>\n<\/tr>\n<tr>\n<td>Letonia<\/td>\n<td>(LV)<\/td>\n<td>Portugal<\/td>\n<td>(PT)<\/td>\n<td>Liechtenstein<\/td>\n<td>(LI)<\/td>\n<td>Irlanda<\/td>\n<td>(IE)<\/td>\n<\/tr>\n<tr>\n<td>Lituania<\/td>\n<td>(LT)<\/td>\n<td>Ruman\u00eda<\/td>\n<td>(RO)<\/td>\n<td>Noruega<\/td>\n<td>(NO)<\/td>\n<td>Grecia<\/td>\n<td>(EL)<\/td>\n<\/tr>\n<tr>\n<td>Luxemburgo<\/td>\n<td>(LU)<\/td>\n<td>Eslovenia<\/td>\n<td>(SI)<\/td>\n<td>Suiza<\/td>\n<td>(CH)<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*Para Suiza podemos crear el expediente PCN, con toda la informaci\u00f3n necesaria para hacer una presentaci\u00f3n en el portal suizo. P\u00f3ngase en contacto con nosotros para obtener m\u00e1s informaci\u00f3n. <\/p>\n<h3>Informaci\u00f3n de la etiqueta CLP<\/h3>\n<p>Le ofrecemos la opci\u00f3n de adquirir una etiqueta de producto conforme a CLP, que contiene toda la informaci\u00f3n obligatoria que exige el Reglamento CLP de la UE. Se le proporcionar\u00e1 en formato PDF.  No se trata de un dise\u00f1o, sino de un resumen de la informaci\u00f3n necesaria. Esto le permitir\u00e1 integrar la informaci\u00f3n necesaria en el dise\u00f1o de la etiqueta de su producto. Tambi\u00e9n puede encargar por separado la <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/etiqueta-clp\/creacion-de-etiquetas-clp-y-comprobacion-del-cumplimiento\/\" target=\"_blank\" title=\"Etiquetado CLPCreaci\u00f3n\">creaci\u00f3n de la etiqueta CLP<\/a>. \u00bfYa tiene una etiqueta? &#8211; Podemos realizar una <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/etiqueta-clp\/creacion-de-etiquetas-clp-y-comprobacion-del-cumplimiento\/\" target=\"_blank\" title=\"Comprobaci\u00f3n del cumplimiento de la etiqueta CLP\">comprobaci\u00f3n de conformidad<\/a> de su etiqueta CLP de acuerdo con los requisitos CLP actuales. Le proporcionaremos informaci\u00f3n detallada y correcciones para garantizar que su etiqueta cumple todas las normas reglamentarias.     <\/p>\n<h2>Registro de velas en el Centro de Toxicolog\u00eda<\/h2>\n<p>Las velas, ya sean perfumadas o no, se utilizan mucho en los hogares y otros entornos para ambientar y decorar. Sin embargo, dado que las velas pueden contener sustancias qu\u00edmicas peligrosas como aceites de fragancia, colorantes u otros aditivos, es necesario registrarlas en el Centro de Toxicolog\u00eda mediante una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP). Este proceso garantiza que el personal de emergencias disponga de la informaci\u00f3n de seguridad necesaria en caso de exposici\u00f3n accidental, ingesti\u00f3n u otros incidentes relacionados con velas. Una NCP proporciona datos esenciales para apoyar respuestas r\u00e1pidas y eficaces durante las emergencias y ayuda a gestionar cualquier riesgo potencial que planteen las velas.   <\/p>\n<h3>\u00bfQu\u00e9 es un UFI?<\/h3>\n<p>Un UFI (Identificador \u00danico de F\u00f3rmula) es un c\u00f3digo \u00fanico asignado a la formulaci\u00f3n de un producto espec\u00edfico, como una vela. Permite a los servicios de emergencia identificar r\u00e1pidamente la composici\u00f3n qu\u00edmica del producto en caso de incidente. En el caso de las velas, esto es especialmente importante, ya que muchas se fabrican con una mezcla de cera, fragancias y colorantes que pueden plantear riesgos en caso de exposici\u00f3n. El UFI ofrece a los profesionales una v\u00eda r\u00e1pida para acceder a los datos de seguridad pertinentes.   <\/p>\n<h3>\u00bfQu\u00e9 es un NCP?<\/h3>\n<p>Una NCP (Notificaci\u00f3n al Centro de Toxicolog\u00eda) es una notificaci\u00f3n al Centro de Toxicolog\u00eda que incluye informaci\u00f3n esencial sobre la seguridad de un producto, como sus ingredientes, peligros, medidas de seguridad y datos de contacto en caso de emergencia. Para las velas, el NCP garantiza la disponibilidad de datos detallados en caso de accidente con el producto, como la ingesti\u00f3n o la exposici\u00f3n qu\u00edmica. Es vital para gestionar estas situaciones de forma eficaz y segura.  <\/p>\n<h3>\u00bfQu\u00e9 es el CLP?<\/h3>\n<p>CLP (Clasificaci\u00f3n, Etiquetado y Envasado) es una normativa de la UE que exige que las sustancias peligrosas se clasifiquen, etiqueten y envasen en funci\u00f3n de sus riesgos. En el caso de las velas, la normativa CLP garantiza que los productos que contienen sustancias qu\u00edmicas peligrosas, como determinados aceites de fragancia o colorantes, est\u00e9n debidamente etiquetados con s\u00edmbolos de peligro, consejos de prudencia e instrucciones de seguridad. El CLP garantiza que los consumidores y los equipos de respuesta a emergencias est\u00e9n informados de los riesgos y de c\u00f3mo manipular los productos de forma segura.  <\/p>\n<h3>\u00bfQu\u00e9 es el Centro de Toxicolog\u00eda?<\/h3>\n<p>El Centro de Toxicolog\u00eda es un recurso centralizado que contiene informaci\u00f3n sobre la seguridad de los productos peligrosos disponibles en toda la UE. Ayuda al personal de emergencias, a los profesionales sanitarios y al p\u00fablico en general a acceder a informaci\u00f3n crucial sobre la seguridad de los productos. En el caso de las velas, el Centro de Toxicolog\u00eda proporciona datos sobre los riesgos potenciales de los ingredientes del producto y ayuda a orientar las acciones de primeros auxilios adecuadas en caso de una emergencia relacionada con el producto.  <\/p>\n<h3>\u00bfPor qu\u00e9 es necesario?<\/h3>\n<p>Debido a los riesgos potenciales que plantean las sustancias qu\u00edmicas utilizadas en las velas perfumadas y no perfumadas, es esencial disponer de una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP). Esta notificaci\u00f3n garantiza que, en caso de una emergencia relacionada con la vela, los equipos de respuesta puedan acceder a informaci\u00f3n vital sobre la composici\u00f3n del producto y las medidas de seguridad apropiadas que se deben tomar. Sin este registro, es posible que los equipos de emergencia no dispongan de todos los detalles necesarios para gestionar un incidente de forma eficaz y segura.  <\/p>\n<h3>\u00bfDesde cu\u00e1ndo es obligatorio por ley?<\/h3>\n<p>La obligaci\u00f3n legal de presentar una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP) para los productos peligrosos, incluidas las velas, pas\u00f3 a ser obligatoria a partir del 1 de enero de 2021. La normativa se aplica a todos los productos peligrosos comercializados en la UE, garantizando que los servicios de emergencia dispongan de la informaci\u00f3n necesaria en caso de emergencia. <\/p>\n<h2>PREGUNTAS FRECUENTES<\/h2>\n<h3>Pregunta: \u00bfEs necesario registrar las velas en el Centro de Toxicolog\u00eda?<\/h3>\n<p>Respuesta: S\u00ed, las velas que contienen sustancias qu\u00edmicas peligrosas, como ciertos aceites de fragancia o colorantes, deben registrarse en el Centro de Toxicolog\u00eda mediante una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP). Esto garantiza que los servicios de emergencia puedan acceder a los datos de seguridad esenciales en caso de incidente o exposici\u00f3n. <\/p>\n<h3>Pregunta: \u00bfCu\u00e1l es la finalidad de un UFI para velas?<\/h3>\n<p>Respuesta: Un UFI (Identificador de F\u00f3rmula \u00danica) es un c\u00f3digo \u00fanico que identifica la formulaci\u00f3n espec\u00edfica de una vela. Esto ayuda a los servicios de emergencia a acceder r\u00e1pidamente a la informaci\u00f3n de seguridad pertinente sobre la composici\u00f3n del producto en caso de accidente o exposici\u00f3n. <\/p>\n<h3>Pregunta: \u00bfPor qu\u00e9 es importante presentar un NCP para las velas?<\/h3>\n<p>Respuesta: La presentaci\u00f3n de un NCP garantiza que la informaci\u00f3n de seguridad esencial sobre la vela, incluidos sus ingredientes, peligros y medidas de respuesta a emergencias, est\u00e9 a disposici\u00f3n de los equipos de respuesta a emergencias. Esto es fundamental para garantizar una gesti\u00f3n r\u00e1pida y eficaz de los incidentes relacionados con velas. <\/p>\n<h3>Pregunta: \u00bfC\u00f3mo se aplica el CLP a las velas?<\/h3>\n<p>Respuesta: De acuerdo con el CLP (Clasificaci\u00f3n, Etiquetado y Envasado), las velas que contienen ingredientes peligrosos deben etiquetarse con los s\u00edmbolos de peligro, las advertencias de seguridad y las instrucciones de manipulaci\u00f3n adecuadas. Esto garantiza que los consumidores y los equipos de respuesta a emergencias conozcan los riesgos asociados a la vela y puedan tomar las precauciones adecuadas. <\/p>\n<h3>Pregunta: \u00bfDesde cu\u00e1ndo es obligatorio presentar un NCP para las velas?<\/h3>\n<p>Respuesta: El requisito legal de presentar una Notificaci\u00f3n al Centro de Toxicolog\u00eda (NCP) para las velas se hizo obligatorio el 1 de enero de 2021, como parte de la normativa de la UE destinada a mejorar la seguridad de los consumidores y la capacidad de respuesta en caso de emergencia.<\/p>\n<h3>Pregunta: \u00bfCu\u00e1nto tiempo se tarda en presentar la notificaci\u00f3n de UFI y PCN?<\/h3>\n<p>Nos lleva unos d\u00edas de trabajo. En cuanto cargue la documentaci\u00f3n, nos pondremos manos a la obra de inmediato. <\/p>\n<h3>Pregunta: \u00bfSoy el propietario de la notificaci\u00f3n de NCP?<\/h3>\n<p>S\u00ed, usted es el propietario de la notificaci\u00f3n de NCP. Usted conserva la plena propiedad de los datos que ha facilitado.  Podr\u00e1 acceder a la notificaci\u00f3n de la NCP en su cuenta de la ECHA.<\/p>\n<h3>Pregunta: \u00bfEste servicio es para un producto o para varios?<\/h3>\n<p>El servicio es para un solo producto.<\/p>\n<h3>Pregunta: \u00bfPor qu\u00e9 tengo que pagar para crear un UFI?<\/h3>\n<p>El servicio que ofrecemos no consiste \u00fanicamente en proporcionar un IUF. El IUF es un componente dentro de un proceso mucho m\u00e1s amplio.  El principal servicio que ofrecemos es la preparaci\u00f3n y presentaci\u00f3n de su Notificaci\u00f3n del Centro de Intoxicaciones (NIP) a los organismos nacionales designados a trav\u00e9s del portal de la ECHA, que es un requisito obligatorio seg\u00fan el Reglamento CLP de la UE para comercializar mezclas peligrosas. Generar un UFI es la parte m\u00e1s sencilla. El informe NCP, sin embargo, es complejo. Exige una revisi\u00f3n detallada de los ingredientes -clasificaciones qu\u00edmicas- formateada con precisi\u00f3n para su presentaci\u00f3n al Centro de Toxicolog\u00eda a trav\u00e9s de la ECHA.   <\/p>\n<h3>Pregunta: Mi empresa no tiene sede en la UE, \u00bfc\u00f3mo puedo presentar un NCP?<\/h3>\n<p>Ofrecemos una soluci\u00f3n para las empresas que no tienen su sede en la UE. Encontrar\u00e1 m\u00e1s informaci\u00f3n en la p\u00e1gina <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/fuera-de-la-ue\/ncp-y-ufi-para-empresas-de-fuera-de-la-ue\/\" target=\"_blank\" rel=\"noopener\">NCP y UFI para empresas no pertenecientes a la UE<\/a>. <\/p>\n<h3>Pregunta: \u00bfPueden proporcionar fichas de datos de seguridad que cumplan plenamente la normativa de la UE (REACH y CLP)?<\/h3>\n<p>S\u00ed, podemos <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/ficha-de-datos-de-seguridad\/servicio-de-creacion-de-fichas-de-datos-de-seguridad-fds-sds\/\" target=\"_blank\"><strong>crear fichas de datos de seguridad (FDS)<\/strong><\/a>&#8211; tambi\u00e9n conocidas como <strong>Fichas de datos de seguridad de materiales (FDS)<\/strong>&#8211; adaptadas a su producto y conformes con las \u00faltimas normativas de la UE. Tanto si fabrica mezclas qu\u00edmicas, como si importa productos a la UE o los distribuye con una etiqueta privada, una FDS que cumpla la normativa es legalmente obligatoria y esencial para un uso seguro en toda la cadena de suministro. Encontrar\u00e1 m\u00e1s informaci\u00f3n en la p\u00e1gina del <a href=\"https:\/\/www.ufi.eu\/es\/pcn\/ficha-de-datos-de-seguridad\/servicio-de-creacion-de-fichas-de-datos-de-seguridad-fds-sds\/\" target=\"_blank\">Servicio de creaci\u00f3n de fichas de datos de seguridad (FDS\/SDS<\/a> ).  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo funciona el servicio de creaci\u00f3n de UFI y notificaci\u00f3n de PCN? Tras adquirir este servicio, recibir\u00e1 acceso al portal seguro. Este portal contiene un resumen de todos los pasos. Rellene los datos de su producto y nos pondremos manos a la obra. Notificaci\u00f3n al Centro de Intoxicaciones y UFI Le proporcionaremos: El identificador \u00fanico [&hellip;]<\/p>\n","protected":false},"featured_media":13987,"template":"","meta":[],"product_brand":[],"product_cat":[366],"product_tag":[],"class_list":{"0":"post-13986","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos-para-el-cuidado-del-aire","8":"first","9":"instock","10":"virtual","11":"taxable","12":"purchasable","13":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}},"regular_price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}}},"bundled_items":[{"bundled_item_id":2606,"product_id":12583,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":2607,"product_id":12572,"menu_order":1,"quantity_min":1,"quantity_max":"","quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":null,"override_description":false,"description":null,"optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PCN y UFI para velas perfumadas y no perfumadas - UFI<\/title>\n<meta name=\"description\" content=\"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCN y UFI para velas perfumadas y no perfumadas\" \/>\n<meta property=\"og:description\" content=\"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Precio\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;0.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilidad\" \/>\n\t<meta name=\"twitter:data2\" content=\"Disponible\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/\",\"url\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/\",\"name\":\"PCN y UFI para velas perfumadas y no perfumadas - UFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg\",\"datePublished\":\"2025-04-16T08:16:58+00:00\",\"description\":\"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.ufi.eu\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCN y UFI para velas perfumadas y no perfumadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"PC-AIR-7\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PCN y UFI para velas perfumadas y no perfumadas - UFI","description":"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/","og_locale":"es_ES","og_type":"article","og_title":"PCN y UFI para velas perfumadas y no perfumadas","og_description":"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.","og_url":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/","og_site_name":"UFI","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Precio":"&euro;0.00","Disponibilidad":"Disponible"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/","url":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/","name":"PCN y UFI para velas perfumadas y no perfumadas - UFI","isPartOf":{"@id":"https:\/\/www.ufi.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg","datePublished":"2025-04-16T08:16:58+00:00","description":"Garantice el cumplimiento del PCN y el UFI para las velas perfumadas y sin perfumar. Nos encargamos de las notificaciones a los centros toxicol\u00f3gicos y de los identificadores de f\u00f3rmula \u00fanica.","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-AIR-7.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/es\/product\/pcn-y-ufi-para-velas-perfumadas-y-no-perfumadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.ufi.eu\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"PCN y UFI para velas perfumadas y no perfumadas"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/es\/#website","url":"https:\/\/www.ufi.eu\/es\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/es\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"PC-AIR-7","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product\/13986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media\/13987"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media?parent=13986"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_brand?post=13986"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_cat?post=13986"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/product_tag?post=13986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}