{"id":30015,"date":"2025-05-14T14:34:08","date_gmt":"2025-05-14T14:34:08","guid":{"rendered":"https:\/\/www.ufi.eu\/sin-categoria\/notificacion-al-centro-de-toxicologia-de-irlanda\/"},"modified":"2025-05-14T14:34:09","modified_gmt":"2025-05-14T14:34:09","slug":"notificacion-al-centro-de-toxicologia-de-irlanda","status":"publish","type":"post","link":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/","title":{"rendered":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda"},"content":{"rendered":"\n<p>\u00bfFabrica o importa mezclas en Irlanda? Entonces necesita comprender y cumplir los requisitos de la <a href=\"https:\/\/www.ufi.eu\/es\/\">Notificaci\u00f3n al Centro de Toxicolog\u00eda<\/a><a href=\"https:\/\/www.ufi.eu\/es\/\">(PCN<\/a>). Esta normativa crucial garantiza que el Centro de Toxicolog\u00eda irland\u00e9s disponga de la informaci\u00f3n necesaria para proporcionar un asesoramiento m\u00e9dico r\u00e1pido y eficaz en caso de emergencia. Navegar por estos requisitos puede ser complejo y llevar mucho tiempo, pero ah\u00ed es donde entramos nosotros.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-understanding-the-importance-of-pcn-in-ireland\">Comprender la importancia del NCP en Irlanda<\/h2>\n\n<p>El objetivo del NCP es sencillo: proteger la salud humana. Al proporcionar informaci\u00f3n detallada sobre la composici\u00f3n de sus mezclas, permite al Centro Irland\u00e9s de Toxicolog\u00eda identificar r\u00e1pidamente los peligros potenciales y recomendar el tratamiento adecuado en caso de exposici\u00f3n accidental. No se trata s\u00f3lo de un obst\u00e1culo reglamentario; es una medida de seguridad vital que salvaguarda a los consumidores y trabajadores de Irlanda. No cumplirla puede acarrear importantes sanciones y, lo que es m\u00e1s importante, poner vidas en peligro.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-deciphering-the-pcn-process-in-ireland-a-complex-landscape\">Descifrando el proceso del NCP en Irlanda: Un paisaje complejo<\/h2>\n\n<p>El proceso de NCP en Irlanda implica presentar informaci\u00f3n detallada sobre sus mezclas, incluida su composici\u00f3n qu\u00edmica, clasificaci\u00f3n, etiquetado y usos previstos. Esta informaci\u00f3n debe presentarse en un formato espec\u00edfico, a menudo a trav\u00e9s de un portal en l\u00ednea espec\u00edfico. Es esencial comprender los matices del Reglamento <a href=\"https:\/\/www.ufi.eu\/pcn\/clp-label\/clp-label-creation-compliance-check\/\">CLP<\/a> y los requisitos espec\u00edficos de las autoridades irlandesas. Esto puede implicar recopilar una gran cantidad de datos, traducir la informaci\u00f3n y garantizar la precisi\u00f3n de toda la documentaci\u00f3n. El proceso puede resultar especialmente dif\u00edcil para las empresas que no est\u00e9n familiarizadas con los entresijos del cumplimiento de la normativa en Irlanda.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-specific-requirements-for-ireland-nbsp-poison-centre-notifications\">Requisitos espec\u00edficos para las notificaciones del Centro de Toxicolog\u00eda de Irlanda<\/h2>\n\n<p>Una vez notificados sus productos a trav\u00e9s del Portal NCP de la ECHA, tambi\u00e9n deber\u00e1 enviar por correo electr\u00f3nico al NPIC una lista de los productos\/mezclas notificados y sus UFI. Adem\u00e1s, el Centro Nacional de Informaci\u00f3n Toxicol\u00f3gica de Irlanda (NPIC) cobra un anticipo anual por el uso de su n\u00famero de tel\u00e9fono en las FDS de los productos qu\u00edmicos comercializados en Irlanda. El anticipo anual es de 650 euros (sin IVA) por empresa (o de 200 euros (sin IVA) si se notifican menos de 10 productos).  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-why-choose-ufi-eu-your-trusted-partner-in-compliance-for-ireland\">\u00bfPor qu\u00e9 elegir UFI.eu? Su socio de confianza en materia de conformidad para Irlanda<\/h2>\n\n<p>Navegar por los requisitos de las NCP en Irlanda no tiene por qu\u00e9 ser un quebradero de cabeza. Ofrecemos un servicio de NCP completo y eficaz que le quita un peso de encima. Somos expertos en la materia, con un profundo conocimiento de la normativa y de los requisitos de las autoridades irlandesas. Deje que nos encarguemos de las complejidades para que usted pueda centrarse en su actividad principal en Irlanda.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-streamlining-the-pcn-process-in-ireland-our-expertise-your-peace-of-mind\">Agilizar el proceso del NCP en Irlanda: Nuestra experiencia, su tranquilidad<\/h2>\n\n<p>Nuestro servicio est\u00e1 dise\u00f1ado para que sea fluido y f\u00e1cil de utilizar. Le guiamos a lo largo de todo el proceso, desde la recopilaci\u00f3n de la informaci\u00f3n necesaria hasta la presentaci\u00f3n de la notificaci\u00f3n. Nos aseguramos de que toda la documentaci\u00f3n sea precisa, est\u00e9 completa y cumpla la normativa m\u00e1s reciente de Irlanda. Comprendemos la importancia de la puntualidad y trabajamos con diligencia para garantizar que sus notificaciones se presenten con prontitud.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-direct-access-to-our-pcn-service-for-ireland-simple-fast-and-reliable\">Acceso directo a nuestro servicio de NCP para Irlanda: Sencillo, r\u00e1pido y fiable<\/h2>\n\n<p>Creemos que el proceso de NCP debe ser lo m\u00e1s sencillo posible. Por eso ofrecemos un sistema de pedido directo a trav\u00e9s de nuestra p\u00e1gina web. Simplemente visite nuestra plataforma, proporcione los detalles necesarios sobre sus mezclas destinadas al mercado irland\u00e9s y nosotros nos encargaremos del resto. Nuestra interfaz intuitiva y el apoyo de nuestros expertos garantizan una experiencia fluida y eficaz.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-key-benefits-of-choosing-our-pcn-service-for-ireland\">Principales ventajas de elegir nuestro servicio de NCP para Irlanda<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Conocimiento experto: Nuestro equipo cuenta con una amplia experiencia en los requisitos de los NCP y el Reglamento <a href=\"https:\/\/www.ufi.eu\/pcn\/clp-label\/clp-label-creation-compliance-check\/\">CLP<\/a>.<\/li>\n\n\n\n<li>Ahorro de tiempo: Libere su valioso tiempo y recursos dejando que nosotros nos encarguemos del proceso.<\/li>\n\n\n\n<li>Precisi\u00f3n y cumplimiento: Nos aseguramos de que sus notificaciones sean precisas y cumplan todos los requisitos normativos.<\/li>\n\n\n\n<li>Reducci\u00f3n de riesgos: Evite sanciones y garantice la seguridad de sus clientes y trabajadores.<\/li>\n\n\n\n<li>Pedidos directos: Nuestra p\u00e1gina web de f\u00e1cil manejo permite realizar pedidos de forma r\u00e1pida y sencilla.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\" id=\"h-ensuring-compliance-in-ireland-more-than-just-a-legal-obligation\">Garantizar el cumplimiento en Irlanda: Algo m\u00e1s que una obligaci\u00f3n legal<\/h2>\n\n<p>Cumplir con los requisitos de los NCP en Irlanda no es s\u00f3lo evitar sanciones; es demostrar su compromiso con la seguridad y las pr\u00e1cticas empresariales responsables en Irlanda. Al garantizar que sus mezclas se notifican correctamente, contribuye a crear un entorno m\u00e1s seguro para todos en Irlanda. Asociarse con nosotros le permite cumplir con sus obligaciones legales de forma eficiente y eficaz, mejorando su reputaci\u00f3n como fabricante o importador responsable en Irlanda.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-take-the-next-step-for-ireland-order-your-pcn-service-today\">D\u00e9 el siguiente paso por Irlanda: Solicite hoy mismo su servicio de NCP<\/h2>\n\n<p>No deje que las complejidades de los requisitos de las NCP en Irlanda le frenen. Nuestro servicio experto le ofrece una soluci\u00f3n fiable y eficaz para Irlanda. Visite nuestro sitio web hoy mismo para obtener m\u00e1s informaci\u00f3n y realizar su pedido. Perm\u00edtanos ser su socio de confianza a la hora de navegar por el panorama normativo de Irlanda, garantizando que sus productos cumplen la normativa y que su negocio est\u00e1 protegido. Estamos aqu\u00ed para simplificar el proceso y darle tranquilidad cuando opere en Irlanda.Solicite su servicio de NCP directamente a trav\u00e9s de <a href=\"https:\/\/www.ufi.eu\/shop\/\" target=\"_blank\" rel=\"noopener\">UFI.eu<\/a> y experimente la facilidad y eficacia de trabajar con expertos.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-national-poison-centre-of-ireland\">Centro Nacional de Toxicolog\u00eda de Irlanda<\/h2>\n\n<p>&#8211; Organismo designado: Centro Nacional de Informaci\u00f3n Toxicol\u00f3gica- P\u00e1gina web: <a href=\"https:\/\/www.poisons.ie\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.poisons.ie\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfFabrica o importa mezclas en Irlanda? Entonces necesita comprender y cumplir los requisitos de la Notificaci\u00f3n al Centro de Toxicolog\u00eda(PCN). Esta normativa crucial garantiza que el Centro de Toxicolog\u00eda irland\u00e9s disponga de la informaci\u00f3n necesaria para proporcionar un asesoramiento m\u00e9dico r\u00e1pido y eficaz en caso de emergencia. Navegar por estos requisitos puede ser complejo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30017,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1254],"tags":[],"class_list":["post-30015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-centros-de-envenenamiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda | Gu\u00eda C<\/title>\n<meta name=\"description\" content=\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda\" \/>\n<meta property=\"og:description\" content=\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-14T14:34:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T14:34:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"chris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\"},\"author\":{\"name\":\"chris\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/5eb803dbe68588e5a9d1a6f45a1c3267\"},\"headline\":\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda\",\"datePublished\":\"2025-05-14T14:34:08+00:00\",\"dateModified\":\"2025-05-14T14:34:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\"},\"wordCount\":997,\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg\",\"articleSection\":[\"Centros de envenenamiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\",\"url\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\",\"name\":\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda | Gu\u00eda C\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg\",\"datePublished\":\"2025-05-14T14:34:08+00:00\",\"dateModified\":\"2025-05-14T14:34:09+00:00\",\"description\":\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg\",\"width\":300,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#website\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/5eb803dbe68588e5a9d1a6f45a1c3267\",\"name\":\"chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aac519d9ad47e589a7f653d592627b4ac55735559c03703b800beebd562f6e5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aac519d9ad47e589a7f653d592627b4ac55735559c03703b800beebd562f6e5e?s=96&d=mm&r=g\",\"caption\":\"chris\"},\"sameAs\":[\"https:\/\/rjbydqrd3t.onrocket.site\"],\"url\":\"https:\/\/www.ufi.eu\/es\/author\/chris\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda | Gu\u00eda C","description":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/","og_locale":"es_ES","og_type":"article","og_title":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda","og_description":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y","og_url":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/","og_site_name":"UFI","article_published_time":"2025-05-14T14:34:08+00:00","article_modified_time":"2025-05-14T14:34:09+00:00","og_image":[{"width":300,"height":180,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg","type":"image\/jpeg"}],"author":"chris","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"chris","Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#article","isPartOf":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/"},"author":{"name":"chris","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/5eb803dbe68588e5a9d1a6f45a1c3267"},"headline":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda","datePublished":"2025-05-14T14:34:08+00:00","dateModified":"2025-05-14T14:34:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/"},"wordCount":997,"publisher":{"@id":"https:\/\/www.ufi.eu\/es\/#organization"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg","articleSection":["Centros de envenenamiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/","url":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/","name":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda | Gu\u00eda C","isPartOf":{"@id":"https:\/\/www.ufi.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg","datePublished":"2025-05-14T14:34:08+00:00","dateModified":"2025-05-14T14:34:09+00:00","description":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda: descubre c\u00f3mo reportar incidentes t\u00f3xicos, procedimientos clave y contacto para una respuesta r\u00e1pida y","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/14.jpg","width":300,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/es\/centros-de-envenenamiento\/notificacion-al-centro-de-toxicologia-de-irlanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Notificaci\u00f3n al Centro de Toxicolog\u00eda de Irlanda"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/es\/#website","url":"https:\/\/www.ufi.eu\/es\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/es\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"},{"@type":"Person","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/5eb803dbe68588e5a9d1a6f45a1c3267","name":"chris","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ufi.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aac519d9ad47e589a7f653d592627b4ac55735559c03703b800beebd562f6e5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac519d9ad47e589a7f653d592627b4ac55735559c03703b800beebd562f6e5e?s=96&d=mm&r=g","caption":"chris"},"sameAs":["https:\/\/rjbydqrd3t.onrocket.site"],"url":"https:\/\/www.ufi.eu\/es\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/posts\/30015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/comments?post=30015"}],"version-history":[{"count":1,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/posts\/30015\/revisions"}],"predecessor-version":[{"id":30020,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/posts\/30015\/revisions\/30020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media\/30017"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/media?parent=30015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/categories?post=30015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/es\/wp-json\/wp\/v2\/tags?post=30015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}