{"id":9364,"date":"2025-03-20T08:24:00","date_gmt":"2025-04-12T21:13:36","guid":{"rendered":"https:\/\/www.ufi.eu\/pcn\/unkategorisiert\/pcn-ufi-fuer-andere-waeschewaschmittel\/"},"modified":"2025-04-17T15:42:45","modified_gmt":"2025-04-17T15:42:45","slug":"pcn-ufi-fuer-andere-waeschewaschmittel","status":"publish","type":"product","link":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/","title":{"rendered":"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel"},"content":{"rendered":"<h2>Wie funktioniert der UFI-Erstellungs- und PCN-Benachrichtigungsdienst?<\/h2>\n<p>Nachdem Sie diesen Service erworben haben, erhalten Sie Zugang zum sicheren Portal. Dieses Portal enth\u00e4lt eine \u00dcbersicht \u00fcber alle Schritte.  Sie geben Ihre Produktdaten ein und wir machen uns an die Arbeit.<\/p>\n<h3>Giftinformationszentrum &amp; UFI<\/h3>\n<p>Wir liefern:<\/p>\n<ul>\n<li>Der Unique Formula Identifier (UFI) f\u00fcr Ihr Produkt<\/li>\n<li>Ein Bericht der Vergiftungszentrale (Poison Centre Notification, PCN)<\/li>\n<li>Registrierung Ihres Produkts bei den zust\u00e4ndigen nationalen Giftnotrufzentralen \u00fcber die ECHA.<\/li>\n<\/ul>\n<h3>L\u00e4nder f\u00fcr die PCN-Registrierung<\/h3>\n<p>Sie k\u00f6nnen die Anzahl der L\u00e4nder z\u00e4hlen, in denen Sie Ihr Produkt registrieren m\u00f6chten. Dies ist die Anzahl der L\u00e4nder, die Sie kaufen m\u00fcssen.  Sie k\u00f6nnen die spezifischen L\u00e4nder innerhalb des Portals ausw\u00e4hlen. Wenn Sie planen, den Verkauf Ihrer Produkte zu einem sp\u00e4teren Zeitpunkt auf neue L\u00e4nder auszuweiten, k\u00f6nnen Sie jederzeit zus\u00e4tzliche <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/lander\/laender-fuer-die-pcn-registrierung\/\" target=\"_blank\" title=\"PCN L\u00e4nderregistrierungen\">PCN-L\u00e4nderregistrierungen<\/a> bestellen.<br \/>Die EU hat 27 L\u00e4nder und der EWR 30 (EU+Lichtenstein, Norwegen und Island). Im Portal k\u00f6nnen Sie diese L\u00e4nder ausw\u00e4hlen: <\/p>\n<table cellpadding=\"2\" cellspacing=\"0\" border=\"1\">\n<tbody>\n<tr>\n<td>Belgien<\/td>\n<td>(BE)<\/td>\n<td>Spanien<\/td>\n<td>(ES)<\/td>\n<td>Ungarn<\/td>\n<td>(HU)<\/td>\n<td>Slowakei<\/td>\n<td>(SK)<\/td>\n<\/tr>\n<tr>\n<td>Bulgarien<\/td>\n<td>(BG)<\/td>\n<td>Frankreich<\/td>\n<td>(FR)<\/td>\n<td>Malta<\/td>\n<td>(MT)<\/td>\n<td>Finnland<\/td>\n<td>(FI)<\/td>\n<\/tr>\n<tr>\n<td>Tschechische Republik<\/td>\n<td>(CZ)<\/td>\n<td>Kroatien<\/td>\n<td>(HR)<\/td>\n<td>Niederlande<\/td>\n<td>(NL)<\/td>\n<td>Schweden<\/td>\n<td>(SE)<\/td>\n<\/tr>\n<tr>\n<td>D\u00e4nemark<\/td>\n<td>(DK)<\/td>\n<td>Italien<\/td>\n<td>(IT)<\/td>\n<td>\u00d6sterreich<\/td>\n<td>(AT)<\/td>\n<td>Deutschland<\/td>\n<td>(DE)<\/td>\n<\/tr>\n<tr>\n<td>Zypern<\/td>\n<td>(CY)<\/td>\n<td>Polen<\/td>\n<td>(PL)<\/td>\n<td>Island<\/td>\n<td>(IS)<\/td>\n<td>Estland<\/td>\n<td>(EE)<\/td>\n<\/tr>\n<tr>\n<td>Lettland<\/td>\n<td>(LV)<\/td>\n<td>Portugal<\/td>\n<td>(PT)<\/td>\n<td>Liechtenstein<\/td>\n<td>(LI)<\/td>\n<td>Irland<\/td>\n<td>(IE)<\/td>\n<\/tr>\n<tr>\n<td>Litauen<\/td>\n<td>(LT)<\/td>\n<td>Rum\u00e4nien<\/td>\n<td>(RO)<\/td>\n<td>Norwegen<\/td>\n<td>(NEIN)<\/td>\n<td>Griechenland<\/td>\n<td>(EL)<\/td>\n<\/tr>\n<tr>\n<td>Luxemburg<\/td>\n<td>(LU)<\/td>\n<td>Slowenien<\/td>\n<td>(SI)<\/td>\n<td>Schweiz*<\/td>\n<td>(CH)<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*F\u00fcr die Schweiz k\u00f6nnen wir das PCN-Dossier mit allen erforderlichen Informationen erstellen, um einen Antrag im Schweizer Portal zu stellen. Kontaktieren Sie uns f\u00fcr weitere Informationen. <\/p>\n<h3>Informationen auf dem CLP-Etikett<\/h3>\n<p>Wir bieten Ihnen die M\u00f6glichkeit, ein CLP-konformes Produktetikett zu erwerben, das alle von der EU-CLP-Verordnung geforderten Informationen enth\u00e4lt. Dieses wird Ihnen als PDF-Datei zur Verf\u00fcgung gestellt.  Dies ist kein Entwurf, sondern eine Zusammenfassung der erforderlichen Informationen. So k\u00f6nnen Sie die erforderlichen Informationen in das Design Ihres Produktetiketts integrieren. Sie k\u00f6nnen die <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/clp-etikett\/erstellung-von-clp-etiketten-ueberpruefung-der-einhaltung-der-vorschriften\/\" target=\"_blank\" title=\"CLP-Etikett-Kreation\">Erstellung des CLP-Etiketts<\/a> auch separat bestellen. Sie haben bereits ein Etikett? &#8211; Wir k\u00f6nnen Ihr Etikett <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/clp-etikett\/erstellung-von-clp-etiketten-ueberpruefung-der-einhaltung-der-vorschriften\/\" target=\"_blank\" title=\"Pr\u00fcfung der Einhaltung der CLP-Kennzeichnung\">auf \u00dcbereinstimmung mit den aktuellen CLP-Anforderungen \u00fcberpr\u00fcfen<\/a>. Wir geben Ihnen detaillierte R\u00fcckmeldungen und Korrekturen, um sicherzustellen, dass Ihr Etikett alle gesetzlichen Vorgaben erf\u00fcllt.     <\/p>\n<h2>Giftinformationszentrum f\u00fcr andere Waschmittel<\/h2>\n<p>Andere Waschmittel, die nicht in die \u00fcblichen Kategorien fallen (wie Standardwaschmittel f\u00fcr den Haushalt oder f\u00fcr den professionellen Gebrauch), k\u00f6nnen dennoch chemische Inhaltsstoffe enthalten, die gem\u00e4\u00df den EU-Vorschriften gef\u00e4hrlich sein k\u00f6nnten. Wenn eine Waschmittelformulierung die Kriterien f\u00fcr die Gefahreneinstufung erf\u00fcllt, muss sie von einer Giftnotrufzentrale (Poison Centre Notification, PCN) gemeldet werden. Durch die Einreichung einer PCN stellen Hersteller und H\u00e4ndler sicher, dass die Giftnotrufzentralen Zugang zu wichtigen Sicherheitsdaten wie der chemischen Zusammensetzung, der Gefahreneinstufung und den Erste-Hilfe-Ma\u00dfnahmen haben, um im Falle einer versehentlichen Exposition eine schnelle und pr\u00e4zise medizinische Reaktion zu erm\u00f6glichen.  <\/p>\n<h3>Was ist ein UFI?<\/h3>\n<p>Der Unique Formula Identifier (UFI) ist ein 16-stelliger alphanumerischer Code, der ein gef\u00e4hrliches Produkt mit seiner genauen chemischen Zusammensetzung verbindet. Bei anderen Waschmitteln, die als gef\u00e4hrlich eingestuft werden, sollte der UFI auf dem Produktetikett angegeben werden, normalerweise in der N\u00e4he von Gefahrensymbolen oder Sicherheitswarnungen. In Notf\u00e4llen verlassen sich die Giftnotrufzentralen auf diesen Code, um die Zusammensetzung des Produkts schnell zu bestimmen und so gezielte und effektive medizinische Hilfe leisten zu k\u00f6nnen.  <\/p>\n<h3>Was ist ein PCN?<\/h3>\n<p>Eine Giftnotrufmeldung (Poison Centre Notification, PCN) ist eine nach EU-Recht vorgeschriebene Meldung f\u00fcr als gef\u00e4hrlich eingestufte chemische Gemische. Im Falle anderer Waschmittel liefert eine PCN den Giftnotrufzentralen wichtige Details, wie z.B. die Inhaltsstoffe des Waschmittels, die Gefahreneinstufung, die Anwendungshinweise und die empfohlenen Erste-Hilfe-Ma\u00dfnahmen. Diese Informationen sind f\u00fcr medizinisches Fachpersonal von entscheidender Bedeutung, um bei einer versehentlichen Exposition schnell und korrekt reagieren zu k\u00f6nnen.  <\/p>\n<h3>Was ist CLP?<\/h3>\n<p>Die Verordnung zur Einstufung, Kennzeichnung und Verpackung (CLP) standardisiert die Identifizierung und Kennzeichnung von Chemikalien in den EU-Mitgliedstaaten. Wenn andere Waschmittel als gef\u00e4hrlich eingestuft sind, muss ihre Verpackung Gefahrensymbole, Risiko-\/Vorsorgehinweise und die UFI enthalten. Diese Kennzeichnung hilft den Benutzern, potenzielle Risiken zu erkennen und geeignete Sicherheitsma\u00dfnahmen zu ergreifen.  <\/p>\n<h3>Was ist die Giftnotrufzentrale?<\/h3>\n<p>Die Giftnotrufzentrale ist ein gemeinsames Netzwerk nationaler Giftnotrufzentralen, das bei Exposition gegen\u00fcber Chemikalien dringenden medizinischen Rat erteilt. Indem Sie ein gef\u00e4hrliches Reinigungsmittel \u00fcber eine PCN bei der Giftnotrufzentrale registrieren, stellen Sie sicher, dass die relevanten Daten den medizinischen Fachkr\u00e4ften zur Verf\u00fcgung stehen, was ein schnelleres und pr\u00e4ziseres Eingreifen erm\u00f6glicht. <\/p>\n<h3>Warum ist das notwendig?<\/h3>\n<p>Andere Waschmittel unterscheiden sich zwar von herk\u00f6mmlichen Waschmitteln f\u00fcr Verbraucher oder professionelle Anwender, k\u00f6nnen aber dennoch L\u00f6sungsmittel, Tenside oder andere Substanzen enthalten, die bei Einatmen, Verschlucken oder Kontakt mit Haut oder Augen gesundheitsgef\u00e4hrdend sind. Ein PCN garantiert, dass die Giftnotrufzentralen die notwendigen Sicherheitsdaten schnell referenzieren k\u00f6nnen, was eine effektive Versorgung und die Einhaltung der EU-Sicherheitsvorschriften erm\u00f6glicht. <\/p>\n<h3>Seit wann ist dies gesetzlich verpflichtend?<\/h3>\n<p>Seit dem 1. Januar 2021 muss jedes gef\u00e4hrliche Chemikaliengemisch, einschlie\u00dflich anderer Waschmittel, gem\u00e4\u00df den CLP-Vorschriften der EU eine PCN einreichen. Diese Gesetzgebung zielt darauf ab, die Sicherheitsstandards zu vereinheitlichen und schnelle Notfallma\u00dfnahmen innerhalb der EU zu gew\u00e4hrleisten. <\/p>\n<h2>FAQ<\/h2>\n<h3>Frage: Ben\u00f6tigen alle &#8220;anderen&#8221; Waschmittel einen PCN?<\/h3>\n<p>Antwort: Nur Produkte, die gem\u00e4\u00df der CLP-Verordnung als gef\u00e4hrlich eingestuft sind, ben\u00f6tigen eine PCN. Wenn das Reinigungsmittel nicht gef\u00e4hrlich ist, ist eine Registrierung nicht erforderlich. <\/p>\n<h3>Frage: Wo befindet sich die UFI auf dem Produktetikett?<\/h3>\n<p>Antwort: Die UFI wird in der Regel in der N\u00e4he von Gefahrenwarnungen oder Sicherheitshinweisen gedruckt, damit sie bei einem Notfall leicht zug\u00e4nglich ist.<\/p>\n<h3>Frage: Welche Informationen m\u00fcssen in einem PCN f\u00fcr diese Detergenzien enthalten sein?<\/h3>\n<p>Antwort: Ein PCN beschreibt die chemische Zusammensetzung des Produkts, die Gefahrenklassifizierung, die empfohlene Erste Hilfe, die Verwendungsrichtlinien und die Verpackungsdetails, damit die Giftnotrufzentralen effektiv reagieren k\u00f6nnen.<\/p>\n<h3>Frage: Wer ist f\u00fcr die Einreichung der PCN verantwortlich?<\/h3>\n<p>Antwort: In der Regel muss der Hersteller, Importeur oder H\u00e4ndler, der das gef\u00e4hrliche Produkt auf den EU-Markt bringt, die PCN-Einreichung vornehmen.<\/p>\n<h3>Frage: Unterliegen auch ungef\u00e4hrliche Detergenzien den PCN-Anforderungen?<\/h3>\n<p>Antwort: Nein, nur Detergenzien, die gem\u00e4\u00df CLP-Verordnung als gef\u00e4hrlich eingestuft sind, unterliegen der PCN-Registrierung. Ungef\u00e4hrliche Detergenzien sind nicht registrierungspflichtig. <\/p>\n<h3>Frage: Was sind die Strafen f\u00fcr das Vers\u00e4umnis, einen PCN einzureichen?<\/h3>\n<p>Antwort: Die Nichteinhaltung kann zu rechtlichen Konsequenzen f\u00fchren, einschlie\u00dflich Geldstrafen oder Produktbeschr\u00e4nkungen, bis die PCN-Verpflichtungen erf\u00fcllt sind.<\/p>\n<h3>Frage: Seit wann ist die PCN-Vorschrift f\u00fcr gef\u00e4hrliche Detergenzien in Kraft?<\/h3>\n<p>Antwort: Die Anforderung wurde am 1. Januar 2021 im Rahmen der EU-CLP-Verordnung eingef\u00fchrt, um die Einheitlichkeit der Notfallprotokolle in den EU-Mitgliedstaaten zu gew\u00e4hrleisten.<\/p>\n<h3>Frage: Wie lange dauert es, die UFI- und PCN-Meldung einzureichen?<\/h3>\n<p>Wir brauchen ein paar Tage Zeit daf\u00fcr. Sobald Sie die Unterlagen hochgeladen haben, fangen wir sofort an. <\/p>\n<h3>Frage: Bin ich der Eigent\u00fcmer der PCN-Benachrichtigung?<\/h3>\n<p>Ja, Sie sind der Eigent\u00fcmer der PCN-Meldung. Sie behalten das volle Eigentum an den von Ihnen bereitgestellten Daten.  Die PCN-Benachrichtigung wird in Ihrem ECHA-Konto zug\u00e4nglich sein.<\/p>\n<h3>Frage: Gilt dieser Service f\u00fcr ein Produkt oder f\u00fcr mehrere?<\/h3>\n<p>Der Service gilt f\u00fcr ein Produkt.<\/p>\n<h3>Frage: Warum muss ich f\u00fcr die Erstellung eines UFI bezahlen?<\/h3>\n<p>Der Service, den wir anbieten, besteht nicht nur in der Bereitstellung einer UFI. Die UFI ist eine Komponente innerhalb eines viel umfassenderen Prozesses.  Die wichtigste Dienstleistung, die wir anbieten, ist die Vorbereitung und Einreichung Ihrer Giftinformationszentrale (PCN) bei den nationalen benannten Stellen \u00fcber das ECHA-Portal. Dies ist gem\u00e4\u00df der CLP-Verordnung der EU eine zwingende Voraussetzung f\u00fcr das Inverkehrbringen gef\u00e4hrlicher Gemische. Die Erstellung einer UFI ist der einfachste Teil. Der PCN-Bericht hingegen ist komplex. Er erfordert eine detaillierte \u00dcberpr\u00fcfung der Inhaltsstoffe &#8211; chemische Klassifizierungen -, die genau f\u00fcr die Einreichung durch die Giftinformationszentrale bei der ECHA formatiert werden m\u00fcssen.   <\/p>\n<h3>Frage: Mein Unternehmen ist nicht in der EU ans\u00e4ssig. Wie kann ich einen PCN einreichen?<\/h3>\n<p>Wir bieten eine L\u00f6sung f\u00fcr Unternehmen, die nicht in der EU ans\u00e4ssig sind. Weitere Informationen finden Sie auf der Seite <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/auserhalb-der-eu\/pcn-ufi-fuer-nicht-eu-unternehmen\/\" target=\"_blank\" rel=\"noopener\">PCN &amp; UFI f\u00fcr Nicht-EU-Unternehmen<\/a>. <\/p>\n<h3>Frage: K\u00f6nnen Sie Sicherheitsdatenbl\u00e4tter in voller \u00dcbereinstimmung mit der EU-Verordnung (REACH &amp; CLP) liefern?<\/h3>\n<p>Ja, wir k\u00f6nnen <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/sicherheitsdatenblatt\/service-zur-erstellung-von-sicherheitsdatenblaettern-msds-sds\/\" target=\"_blank\"><strong>Sicherheitsdatenbl\u00e4tter (SDS) erstellen<\/strong><\/a>&#8211; auch bekannt als <strong>Sicherheitsdatenbl\u00e4tter (MSDS)<\/strong>&#8211; erstellen, die auf Ihr Produkt zugeschnitten sind und den neuesten EU-Vorschriften entsprechen. Unabh\u00e4ngig davon, ob Sie chemische Gemische herstellen, Produkte in die EU importieren oder unter einer Eigenmarke vertreiben, ist ein konformes SDB gesetzlich vorgeschrieben und f\u00fcr die sichere Verwendung in der gesamten Lieferkette unerl\u00e4sslich. Weitere Informationen finden Sie auf der Seite <a href=\"https:\/\/www.ufi.eu\/de\/pcn\/sicherheitsdatenblatt\/service-zur-erstellung-von-sicherheitsdatenblaettern-msds-sds\/\" target=\"_blank\">Service zur Erstellung von Sicherheitsdatenbl\u00e4ttern (MSDS\/SDS)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie funktioniert der UFI-Erstellungs- und PCN-Benachrichtigungsdienst? Nachdem Sie diesen Service erworben haben, erhalten Sie Zugang zum sicheren Portal. Dieses Portal enth\u00e4lt eine \u00dcbersicht \u00fcber alle Schritte. Sie geben Ihre Produktdaten ein und wir machen uns an die Arbeit. Giftinformationszentrum &amp; UFI Wir liefern: Der Unique Formula Identifier (UFI) f\u00fcr Ihr Produkt Ein Bericht der Vergiftungszentrale [&hellip;]<\/p>\n","protected":false},"featured_media":9365,"template":"","meta":[],"product_brand":[],"product_cat":[158],"product_tag":[],"class_list":{"0":"post-9364","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-waschewaschmittel","8":"first","9":"instock","10":"virtual","11":"taxable","12":"purchasable","13":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}},"regular_price":{"min":{"incl_tax":"121","excl_tax":"100"},"max":{"incl_tax":"","excl_tax":""}}},"bundled_items":[{"bundled_item_id":1082,"product_id":8696,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":"Giftinformationszentrum &amp; UFI","override_description":false,"description":"Giftinformationszentrum &amp; UFI","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":1083,"product_id":8698,"menu_order":1,"quantity_min":1,"quantity_max":"","quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":"L\u00e4nder f\u00fcr die PCN-Registrierung","override_description":false,"description":"L\u00e4nder f\u00fcr die PCN-Registrierung","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[""],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.1 (Yoast SEO v25.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel - UFI<\/title>\n<meta name=\"description\" content=\"Erhalten Sie eine PCN &amp; UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel\" \/>\n<meta property=\"og:description\" content=\"Erhalten Sie eine PCN &amp; UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/\" \/>\n<meta property=\"og:site_name\" content=\"UFI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-17T15:42:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;0.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/\",\"url\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/\",\"name\":\"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel - UFI\",\"isPartOf\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg\",\"datePublished\":\"2025-04-12T21:13:36+00:00\",\"dateModified\":\"2025-04-17T15:42:45+00:00\",\"description\":\"Erhalten Sie eine PCN & UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ufi.eu\/de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.ufi.eu\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ufi.eu\/de\/#website\",\"url\":\"https:\/\/www.ufi.eu\/de\/\",\"name\":\"UFI.EU\",\"description\":\"Poison Centre Notifications (PCN) and UFI\",\"publisher\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ufi.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ufi.eu\/de\/#organization\",\"name\":\"UFI.EU\",\"url\":\"https:\/\/www.ufi.eu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.ufi.eu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"contentUrl\":\"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg\",\"width\":231,\"height\":78,\"caption\":\"UFI.EU\"},\"image\":{\"@id\":\"https:\/\/www.ufi.eu\/de\/#\/schema\/logo\/image\/\"},\"description\":\"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.\",\"email\":\"info@ufi.eu\",\"legalName\":\"UFI.EU\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"PC-DET-1_OTH\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel - UFI","description":"Erhalten Sie eine PCN & UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/","og_locale":"de_DE","og_type":"article","og_title":"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel","og_description":"Erhalten Sie eine PCN & UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!","og_url":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/","og_site_name":"UFI","article_modified_time":"2025-04-17T15:42:45+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&euro;0.00","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/","url":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/","name":"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel - UFI","isPartOf":{"@id":"https:\/\/www.ufi.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage"},"image":{"@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg","datePublished":"2025-04-12T21:13:36+00:00","dateModified":"2025-04-17T15:42:45+00:00","description":"Erhalten Sie eine PCN & UFI f\u00fcr andere Waschmittel. Stellen Sie mit unserem schnellen und zuverl\u00e4ssigen Benachrichtigungsservice sicher, dass die EU-Giftinformationszentrale eingehalten wird!","breadcrumb":{"@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#primaryimage","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/PC-DET-1_OTH.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ufi.eu\/de\/product\/pcn-ufi-fuer-andere-waeschewaschmittel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ufi.eu\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.ufi.eu\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"PCN &amp; UFI f\u00fcr andere W\u00e4schewaschmittel"}]},{"@type":"WebSite","@id":"https:\/\/www.ufi.eu\/de\/#website","url":"https:\/\/www.ufi.eu\/de\/","name":"UFI.EU","description":"Poison Centre Notifications (PCN) and UFI","publisher":{"@id":"https:\/\/www.ufi.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ufi.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.ufi.eu\/de\/#organization","name":"UFI.EU","url":"https:\/\/www.ufi.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ufi.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","contentUrl":"https:\/\/www.ufi.eu\/wp-content\/uploads\/2025\/03\/cropped-logo_ufi3.jpg","width":231,"height":78,"caption":"UFI.EU"},"image":{"@id":"https:\/\/www.ufi.eu\/de\/#\/schema\/logo\/image\/"},"description":"UFI.eu specializes in digital registrations for Poison Centre Notifications (PCN), ensuring your chemical products meet EU regulatory requirements effortlessly. Our streamlined solutions help businesses stay compliant while reducing complexity and administrative burden.","email":"info@ufi.eu","legalName":"UFI.EU"}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"PC-DET-1_OTH","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/product\/9364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/media\/9365"}],"wp:attachment":[{"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/media?parent=9364"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/product_brand?post=9364"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/product_cat?post=9364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ufi.eu\/de\/wp-json\/wp\/v2\/product_tag?post=9364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}